{"id":80590,"date":"2020-10-01T14:28:53","date_gmt":"2020-10-01T12:28:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=80590&#038;preview=true&#038;preview_id=80590"},"modified":"2021-10-15T14:11:27","modified_gmt":"2021-10-15T12:11:27","slug":"equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/","title":{"rendered":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&rsquo;octobre"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FOOTBALL &#8211; Didier <\/em><\/strong><b><i>Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les trois matchs de l&rsquo;<a href=\"https:\/\/dicodusport.fr\/blog\/tag\/equipe-de-france-de-football\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00e9quipe de France<\/a> pr\u00e9vus au d\u00e9but de ce mois d&rsquo;octobre 2020.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Les Bleus d\u00e9buteront par un match amical face \u00e0 l&rsquo;<strong>Ukraine<\/strong> (7\/10, 21h10), avant de recevoir le <strong>Portugal<\/strong> (11\/10, 20h45) et d&rsquo;aller en <strong>Croatie<\/strong> (14\/10, 20h45) dans le cadre de la Ligue des Nations. <strong>Houssem Aouar<\/strong> pourrait enfin conna\u00eetre sa premi\u00e8re s\u00e9lection, puisque le milieu de terrain lyonnais a \u00e9t\u00e9 rappel\u00e9 apr\u00e8s son forfait pour le dernier rassemblement. <strong>Paul Pogba<\/strong> fait lui son retour dans le groupe alors qu&rsquo;<strong>Eduardo Camavinga<\/strong> est reconduit apr\u00e8s sa bonne entr\u00e9e en jeu face \u00e0 la Croatie en septembre. <strong>Adrien Rabiot<\/strong> est aussi pr\u00e9sent, tout comme <strong>Dayot Upamecano<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">RDV lundi \u00e0 Clairefontaine pour pr\u00e9parer les 3 matchs qui nous attendent ! &#x1f44a; &#x1f1fa;&#x1f1e6;&#x1f1f5;&#x1f1f9;&#x1f1ed;&#x1f1f7; <a href=\"https:\/\/twitter.com\/hashtag\/FiersdetreBleus?src=hash&amp;ref_src=twsrc%5Etfw\">#FiersdetreBleus<\/a> <a href=\"https:\/\/t.co\/1mzaPaTYGD\">pic.twitter.com\/1mzaPaTYGD<\/a><\/p>\n<p>\u2014 Equipe de France &#x2b50;&#x2b50; (@equipedefrance) <a href=\"https:\/\/twitter.com\/equipedefrance\/status\/1311638134795497473?ref_src=twsrc%5Etfw\">October 1, 2020<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOOTBALL &#8211; Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les trois matchs de l&rsquo;\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d&rsquo;octobre 2020.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":80594,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[523,199,75],"class_list":["post-80590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-bleus","tag-equipe-de-france","tag-football"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&#039;octobre<\/title>\n<meta name=\"description\" content=\"FOOTBALL - Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les 3 matchs de l&#039;\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d&#039;octobre 2020.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&#039;octobre\" \/>\n<meta property=\"og:description\" content=\"FOOTBALL - Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les 3 matchs de l&#039;\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d&#039;octobre 2020.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-01T12:28:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-15T12:11:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&#039;octobre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&rsquo;octobre\",\"datePublished\":\"2020-10-01T12:28:53+00:00\",\"dateModified\":\"2021-10-15T12:11:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\"},\"wordCount\":190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png\",\"keywords\":[\"bleus\",\"\u00c9quipe de France\",\"Football\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\",\"name\":\"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d'octobre\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png\",\"datePublished\":\"2020-10-01T12:28:53+00:00\",\"dateModified\":\"2021-10-15T12:11:27+00:00\",\"description\":\"FOOTBALL - Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les 3 matchs de l'\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d'octobre 2020.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png\",\"width\":800,\"height\":445,\"caption\":\"La liste des Bleuets pour la phase de groupe de l'Euro Espoirs d\u00e9voil\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&rsquo;octobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d'octobre","description":"FOOTBALL - Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les 3 matchs de l'\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d'octobre 2020.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d'octobre","og_description":"FOOTBALL - Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les 3 matchs de l'\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d'octobre 2020.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-10-01T12:28:53+00:00","article_modified_time":"2021-10-15T12:11:27+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d'octobre","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&rsquo;octobre","datePublished":"2020-10-01T12:28:53+00:00","dateModified":"2021-10-15T12:11:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/"},"wordCount":190,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png","keywords":["bleus","\u00c9quipe de France","Football"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/","url":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/","name":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d'octobre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png","datePublished":"2020-10-01T12:28:53+00:00","dateModified":"2021-10-15T12:11:27+00:00","description":"FOOTBALL - Didier Deschamps a d\u00e9voil\u00e9 sa liste de 24 joueurs pour les 3 matchs de l'\u00e9quipe de France pr\u00e9vus au d\u00e9but de ce mois d'octobre 2020.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/\u00c9quipe-de-France-Les-Bleus-avec-Aouar-Pogba-et-Camavinga-pour-les-matchs-doctobre.png","width":800,"height":445,"caption":"La liste des Bleuets pour la phase de groupe de l'Euro Espoirs d\u00e9voil\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/equipe-de-france-les-bleus-avec-aouar-pogba-camavinga-matchs-octobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipe de France : les Bleus avec Aouar, Pogba et Camavinga pour les matchs d&rsquo;octobre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/80590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=80590"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/80590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/80594"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=80590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=80590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=80590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}