{"id":81473,"date":"2020-10-07T11:00:39","date_gmt":"2020-10-07T09:00:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=81473"},"modified":"2020-10-07T15:46:15","modified_gmt":"2020-10-07T13:46:15","slug":"ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/","title":{"rendered":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, <a href=\"https:\/\/dicodusport.fr\/blog\/le-mythique-rc-lens-retrouve-la-ligue-1\/\" target=\"_blank\" rel=\"noopener noreferrer\">le promu lensois<\/a> r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002, avec 13 points engrang\u00e9s sur 18 possibles. Avant le derby face \u00e0 Lille lors de la prochaine journ\u00e9e, retour sur la r\u00e9ussite du RC Lens en ce d\u00e9but de saison.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Le recrutement du RC Lens fonctionne d\u00e9j\u00e0<\/h2>\n<p style=\"text-align: justify;\">Nous sommes en 2001\/2002, lorsque les Sikora, Wallemme et Diouf terminaient 2<sup>\u00e8mes<\/sup> du championnat derri\u00e8re Lyon avec un d\u00e9but de championnat tambours battants. Un fort souvenir pour les supporters Sang et Or qui revivent cette saison un d\u00e9but de championnat tr\u00e8s int\u00e9ressant de leurs poulains. Alors le <b>RC Lens<\/b> ne terminera certainement pas 2<sup>\u00e8me<\/sup>, mais le promu a montr\u00e9 de vrais arguments sur les 6 premi\u00e8res rencontres de <b>Ligue 1 Uber Eats<\/b> (4 victoires, 1 nul, 1 d\u00e9faite).<\/p>\n<p style=\"text-align: justify;\">Le <b>RC Lens<\/b> a pris l\u2019habitude de voir ses joueurs plac\u00e9s dans le 11 type de chaque journ\u00e9e de <b>Ligue 1 Uber Eats<\/b> par le journal <em>L\u2019\u00c9quipe <\/em>et c\u2019est tout sauf une anomalie\u00a0: <em>\u00ab<\/em>\u00a0<em>J\u2019ai un tr\u00e8s bon groupe et il y a eu un tr\u00e8s bon recrutement<\/em>\u00a0<em>\u00bb<\/em> disait le coach lensois <b>Franck Haise<\/b> apr\u00e8s la victoire logique ce week-end face \u00e0 <b>Saint-Etienne<\/b>. Il est vrai que le mercato du <b>RC Lens<\/b> s\u2019est fait ressentir rapidement, avec les\u00a08 buts inscrits par <b>Ganago<\/b> (4 buts, ex Nice) et <b>Kakuta<\/b> (4 buts, ex Rayo Vallecano) sur les 10 buts inscrits par les joueurs du Pas-de-Calais. Ceci combin\u00e9 aux bonnes performances de <b>Medina<\/b> (ex Talleres), <b>Bad\u00e9<\/b> (ex Le Havre), <b>Clauss<\/b> (ex Arminia Bielefeld) et <b>Sylla<\/b> (ex Toulouse). En attendant les vrais d\u00e9buts de <b>Seko Fofana<\/b> (ex Udinese), recrue la plus ch\u00e8re de l\u2019histoire du RCL (10 millions \u20ac), encore bless\u00e9 aux ischios-jambiers.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u00ab\u00a0H\u00e2te d&rsquo;y \u00eatre !\u00a0\u00bb<a href=\"https:\/\/twitter.com\/hashtag\/Mercato?src=hash&amp;ref_src=twsrc%5Etfw\">#Mercato<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Guid%C3%A9sParNotreFiert%C3%A9?src=hash&amp;ref_src=twsrc%5Etfw\">#Guid\u00e9sParNotreFiert\u00e9<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/rclens?src=hash&amp;ref_src=twsrc%5Etfw\">#rclens<\/a> <a href=\"https:\/\/t.co\/lS7CrNx5N1\">pic.twitter.com\/lS7CrNx5N1<\/a><\/p>\n<p>\u2014 Racing Club de Lens (@RCLens) <a href=\"https:\/\/twitter.com\/RCLens\/status\/1295700877156769794?ref_src=twsrc%5Etfw\">August 18, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le fil rouge de Franck Haise\u00a0: jeu et \u00e9tat d\u2019esprit<\/h2>\n<p style=\"text-align: justify;\">Comme le conc\u00e9dait Jean-Louis Gasset lors de la d\u00e9faite de <b>Bordeaux<\/b> \u00e0 <b>Lens<\/b> (2-1 le 19 septembre dernier)\u00a0: \u00ab\u00a0<em>Ils sont tr\u00e8s bien organis\u00e9s, tr\u00e8s agressifs, s\u00fbrs de leur jeu<\/em>\u00a0\u00bb. Ce constat, beaucoup d\u2019entra\u00eeneurs de <b>Ligue 1 Uber Eats<\/b> ont d\u00fb le faire en visionnant les rencontres du <b>RC Lens<\/b>. Depuis la d\u00e9faite en ouverture \u00e0 <b>Nice<\/b>, les Lensois font preuve d\u2019un \u00e9tat d\u2019esprit remarquable sur le terrain, m\u00ealant agressivit\u00e9 (16 cartons jaune en 6 matchs) et jeu offensif assum\u00e9. Apr\u00e8s 5 saisons en Ligue 2, le <b>RC Lens<\/b> se voit rester en <b>Ligue 1 Uber Eats<\/b> en \u00e9tant ma\u00eetre de son destin et en jouant au maximum.<\/p>\n<div id=\"attachment_81479\" style=\"width: 698px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-81479\" class=\"wp-image-81479 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/RC-Lens-PSG.jpg\" alt=\"\" width=\"688\" height=\"507\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/RC-Lens-PSG.jpg 688w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/RC-Lens-PSG-300x221.jpg 300w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><p id=\"caption-attachment-81479\" class=\"wp-caption-text\">Le RC Lens a domin\u00e9 le PSG \u00e0 Bollaert (1-0) en d\u00e9but de saison &#8211; AFP<\/p><\/div>\n<p style=\"text-align: justify;\"><em><strong>Romain Delanis<br \/>\n<\/strong><\/em><em><strong><a href=\"https:\/\/twitter.com\/RDelanis\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le promu lensois r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002, avec 13 points engrang\u00e9s sur 18 possibles. Avant le derby face \u00e0 Lille lors de la prochaine journ\u00e9e, retour sur la r\u00e9ussite du RC Lens en ce d\u00e9but de saison.<\/p>\n","protected":false},"author":14,"featured_media":81592,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[75,1554,11079,3709,24],"class_list":["post-81473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-ligue-1","tag-ligue-1-uber-eats","tag-rc-lens","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le RC Lens r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le RC Lens r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-07T09:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-07T13:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Romain Delanis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/RDelanis\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\"},\"author\":{\"name\":\"Romain Delanis\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8c78730a59f8a1e617f7a19026ebc14a\"},\"headline\":\"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite\",\"datePublished\":\"2020-10-07T09:00:39+00:00\",\"dateModified\":\"2020-10-07T13:46:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\"},\"wordCount\":476,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png\",\"keywords\":[\"Football\",\"Ligue 1\",\"Ligue 1 Uber Eats\",\"RC Lens\",\"sport\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\",\"name\":\"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png\",\"datePublished\":\"2020-10-07T09:00:39+00:00\",\"dateModified\":\"2020-10-07T13:46:15+00:00\",\"description\":\"Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le RC Lens r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png\",\"width\":800,\"height\":445,\"caption\":\"Ligue 1 - Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8c78730a59f8a1e617f7a19026ebc14a\",\"name\":\"Romain Delanis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Romain-Delanis-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Romain-Delanis-150x150.jpg\",\"caption\":\"Romain Delanis\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis novembre 2015 - Capable de passer un samedi apr\u00e8s-midi devant la Ligue 2 puis le biathlon sans oublier la finale de l\u2019ATP Rotterdam, j\u2019aime aussi mettre mon r\u00e9veil pour me faire un Pistons\/Bulls qui rappelle de bons souvenirs. Tout cela, j\u2019ai choisi il y a maintenant quelques temps de vous le raconter avec Dicodusport, pour vous faire vivre ma passion parfois inconsid\u00e9r\u00e9e pour le sport en g\u00e9n\u00e9ral (mais surtout le foot faut se l\u2019avouer).\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/RDelanis\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/romain\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite","description":"Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le RC Lens r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite","og_description":"Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le RC Lens r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-10-07T09:00:39+00:00","article_modified_time":"2020-10-07T13:46:15+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png","type":"image\/png"}],"author":"Romain Delanis","twitter_card":"summary_large_image","twitter_title":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite","twitter_creator":"@https:\/\/twitter.com\/RDelanis","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/"},"author":{"name":"Romain Delanis","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8c78730a59f8a1e617f7a19026ebc14a"},"headline":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite","datePublished":"2020-10-07T09:00:39+00:00","dateModified":"2020-10-07T13:46:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/"},"wordCount":476,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png","keywords":["Football","Ligue 1","Ligue 1 Uber Eats","RC Lens","sport"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/","name":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png","datePublished":"2020-10-07T09:00:39+00:00","dateModified":"2020-10-07T13:46:15+00:00","description":"Apr\u00e8s 6 journ\u00e9es de Ligue 1 Uber Eats, le RC Lens r\u00e9alise son meilleur d\u00e9but de saison dans l\u2019\u00e9lite depuis 2001\/2002.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Ligue-1-Le-RC-Lens-d\u00e9marre-fort-pour-son-retour-dans-l\u2019\u00e9lite.png","width":800,"height":445,"caption":"Ligue 1 - Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-le-rc-lens-demarre-fort-pour-son-retour-dans-l-elite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 : Le RC Lens d\u00e9marre fort pour son retour dans l\u2019\u00e9lite"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8c78730a59f8a1e617f7a19026ebc14a","name":"Romain Delanis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Romain-Delanis-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Romain-Delanis-150x150.jpg","caption":"Romain Delanis"},"description":"Journaliste\/R\u00e9dacteur depuis novembre 2015 - Capable de passer un samedi apr\u00e8s-midi devant la Ligue 2 puis le biathlon sans oublier la finale de l\u2019ATP Rotterdam, j\u2019aime aussi mettre mon r\u00e9veil pour me faire un Pistons\/Bulls qui rappelle de bons souvenirs. Tout cela, j\u2019ai choisi il y a maintenant quelques temps de vous le raconter avec Dicodusport, pour vous faire vivre ma passion parfois inconsid\u00e9r\u00e9e pour le sport en g\u00e9n\u00e9ral (mais surtout le foot faut se l\u2019avouer).","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/RDelanis"],"url":"https:\/\/dicodusport.fr\/blog\/author\/romain\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/81473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=81473"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/81473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/81592"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=81473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=81473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=81473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}