{"id":81866,"date":"2020-10-08T19:10:02","date_gmt":"2020-10-08T17:10:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=81866&#038;preview=true&#038;preview_id=81866"},"modified":"2020-10-08T20:11:14","modified_gmt":"2020-10-08T18:11:14","slug":"roland-garros-2020-programme-matchs-vendredi-9-octobre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/","title":{"rendered":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis\/roland-garros-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">ROLAND-GARROS 2020<\/a> &#8211; D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Court Philippe-Chatrier (D\u00e8s 14h50)<\/h2>\n<p>Diego Schwartzman (ARG &#8211; n\u00b012) &#8211; Rafael Nadal (ESP &#8211; n\u00b02)<br \/>\n<strong>Pas avant 17h :<\/strong> Novak Djokovic (SER &#8211; n\u00b01) &#8211; Stefanos Tsitsipas (GRE &#8211; n\u00b05)<\/p>\n<h2 style=\"text-align: justify;\">Court Suzanne-Lenglen (D\u00e8s 11h)<\/h2>\n<p>B.Krejcikova\/K.Siniakova (n\u00b04) &#8211; T.Babos\/<strong>K.Mladenovic<\/strong> (n\u00b02)<br \/>\nA.Guarachi\/D.Krawczyk (n\u00b014) &#8211; N.Melichar\/I.Swiatek<\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS 2020 &#8211; D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.<\/p>\n","protected":false},"author":1,"featured_media":81731,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47090],"tags":[159],"class_list":["post-81866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-roland-garros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS 2020 - D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS 2020 - D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-08T17:10:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T18:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre\",\"datePublished\":\"2020-10-08T17:10:02+00:00\",\"dateModified\":\"2020-10-08T18:11:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\"},\"wordCount\":80,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png\",\"keywords\":[\"Roland-Garros\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\",\"name\":\"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png\",\"datePublished\":\"2020-10-08T17:10:02+00:00\",\"dateModified\":\"2020-10-08T18:11:14+00:00\",\"description\":\"ROLAND-GARROS 2020 - D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre","description":"ROLAND-GARROS 2020 - D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre","og_description":"ROLAND-GARROS 2020 - D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-10-08T17:10:02+00:00","article_modified_time":"2020-10-08T18:11:14+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre","datePublished":"2020-10-08T17:10:02+00:00","dateModified":"2020-10-08T18:11:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/"},"wordCount":80,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png","keywords":["Roland-Garros"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/","name":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png","datePublished":"2020-10-08T17:10:02+00:00","dateModified":"2020-10-08T18:11:14+00:00","description":"ROLAND-GARROS 2020 - D\u00e9couvrez le programme des matchs des principaux courts de ce vendredi 9 octobre 2020.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Roland-Garros-9-octobre.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2020-programme-matchs-vendredi-9-octobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros 2020 : le programme des matchs du vendredi 9 octobre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/81866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=81866"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/81866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/81731"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=81866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=81866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=81866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}