{"id":82110,"date":"2020-10-10T13:46:22","date_gmt":"2020-10-10T11:46:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=82110&#038;preview=true&#038;preview_id=82110"},"modified":"2021-05-11T17:07:19","modified_gmt":"2021-05-11T15:07:19","slug":"roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/","title":{"rendered":"Roland-Garros : notre pronostic pour Novak Djokovic &#8211; Rafael Nadal"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/tennis\/roland-garros-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>ROLAND-GARROS 2020<\/strong><\/a><b> &#8211; Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Novak Djokovic &#8211; Rafael Nadal : Dimanche 11 octobre, 15h00<\/span><\/h2>\n<p style=\"text-align: justify;\">Rafael Nadal n&rsquo;a fait qu&rsquo;une bouch\u00e9e de Diego Schwartzman, m\u00eame si l&rsquo;Argentin l&rsquo;a pouss\u00e9 dans le tie-break au troisi\u00e8me set. M\u00eame quand l&rsquo;Espagnol a des temps faibles, il parvient \u00e0 faire le n\u00e9cessaire pour rester devant au score et n&rsquo;a toujours pas perdu le moindre set depuis le d\u00e9but de la quinzaine. Novak Djokovic a d&rsquo;abord d\u00e9roul\u00e9 face \u00e0 Stefanos Tsitsipas avant de coincer et conc\u00e9der deux manches. Contre le ma\u00eetre des lieux, ce sera encore un autre niveau et si le Serbe semble pouvoir accrocher un set, ce sera compliqu\u00e9 de faire plus. <strong>On part sur une victoire et un sacre de Rafael Nadal.<\/strong><\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; height: 23px; vertical-align: middle; width: 600px;\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 11 octobre, 15h00<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; text-align: center; vertical-align: middle; width: 100px;\"><span style=\"color: #ffffff;\">1<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; text-align: center; vertical-align: middle; width: 100px;\"><span style=\"color: #ffffff;\">2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; height: 47px; width: 600px;\"><strong>Novak Djokovic &#8211; Rafael Nadal<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; height: 47px; text-align: center; vertical-align: middle; width: 100px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/23920081?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 2.35<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; height: 47px; text-align: center; vertical-align: middle; width: 100px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/23920081?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> 1.60<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\" href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif; font-size: 16px;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS &#8211; Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.<\/p>\n","protected":false},"author":1,"featured_media":82114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47090],"tags":[3224,4949,3223,159],"class_list":["post-82110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-novak-djokovic","tag-pronostics","tag-rafael-nadal","tag-roland-garros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal - Dicodusport<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS - Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS - Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-10T11:46:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T15:07:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Roland-Garros : notre pronostic pour Novak Djokovic &#8211; Rafael Nadal\",\"datePublished\":\"2020-10-10T11:46:22+00:00\",\"dateModified\":\"2021-05-11T15:07:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png\",\"keywords\":[\"Novak Djokovic\",\"Pronostics\",\"Rafael Nadal\",\"Roland-Garros\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\",\"name\":\"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png\",\"datePublished\":\"2020-10-10T11:46:22+00:00\",\"dateModified\":\"2021-05-11T15:07:19+00:00\",\"description\":\"ROLAND-GARROS - Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros : notre pronostic pour Novak Djokovic &#8211; Rafael Nadal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal - Dicodusport","description":"ROLAND-GARROS - Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal","og_description":"ROLAND-GARROS - Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-10-10T11:46:22+00:00","article_modified_time":"2021-05-11T15:07:19+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Roland-Garros : notre pronostic pour Novak Djokovic &#8211; Rafael Nadal","datePublished":"2020-10-10T11:46:22+00:00","dateModified":"2021-05-11T15:07:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png","keywords":["Novak Djokovic","Pronostics","Rafael Nadal","Roland-Garros"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/","name":"Roland-Garros : notre pronostic pour Novak Djokovic - Rafael Nadal - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png","datePublished":"2020-10-10T11:46:22+00:00","dateModified":"2021-05-11T15:07:19+00:00","description":"ROLAND-GARROS - Novak Djokovic d\u00e9fie Rafael Nadal en finale de Roland-Garros. Notre pronostic pour le match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Finale-Roland-Garros-2020-notre-pronostic-pour-Novak-Djokovic-Rafael-Nadal.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-notre-pronostic-pour-novak-djokovic-rafael-nadal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros : notre pronostic pour Novak Djokovic &#8211; Rafael Nadal"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/82110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=82110"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/82110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/82114"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=82110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=82110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=82110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}