{"id":83975,"date":"2020-10-21T17:48:02","date_gmt":"2020-10-21T15:48:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=83975&#038;preview=true&#038;preview_id=83975"},"modified":"2020-10-21T19:42:22","modified_gmt":"2020-10-21T17:42:22","slug":"tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/","title":{"rendered":"Tour d&rsquo;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/tour-d-espagne-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">TOUR D&rsquo;ESPAGNE 2020<\/a> &#8211; En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri. Le vainqueur de Paris-Nice en 2018, qui a fait le boulot pour Alejandro Valverde et Enric Mas dans la derni\u00e8re difficult\u00e9 du jour, a devanc\u00e9 Primoz Roglic, qui a r\u00e9gl\u00e9 le groupe des cadors.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s deux \u00e9tapes, la <strong>Vuelta 2020<\/strong> est d\u00e9j\u00e0 bien lanc\u00e9e, et on y voit d\u00e9j\u00e0 plus clair dans l&rsquo;optique du classement g\u00e9n\u00e9ral. Comme ce mardi vers Eibar, une difficult\u00e9 est venue animer le final, avec cette fois, l&rsquo;Alto de San Miguel de Aralar en (presque) juge de paix, avec le sommet \u00e0 17 km de l&rsquo;arriv\u00e9e. Et ce mercredi, la <strong>Movistar<\/strong> a \u00e9t\u00e9 r\u00e9compens\u00e9e pour son travail tout au long de la journ\u00e9e. Un premier coup de bordure \u00e0 70 km de l&rsquo;arriv\u00e9e, condamnant notamment <strong>Guillaume Martin<\/strong> (Cofidis), avant un r\u00e9cital dans le final.<\/p>\n<h2 style=\"text-align: justify;\">Soler rayonne<\/h2>\n<p style=\"text-align: justify;\">Aux manettes, un certain <strong>Marc Soler<\/strong>. Le laur\u00e9at de <em>la Course au Soleil<\/em> en 2018 faisait un gros tempo dans San Miguel de Aralar, pour <strong>Enric Mas<\/strong>, son leader, et <strong>Alejandro Valverde<\/strong>, en course pour une 13\u00e8me victoire d&rsquo;\u00e9tape sur la Vuelta. Apr\u00e8s s&rsquo;\u00eatre \u00e9cart\u00e9, Soler voyait <strong>Richard Carapaz<\/strong> (INEOS Grenadiers), d\u00e9j\u00e0 \u00e0 l&rsquo;attaque au pied de la difficult\u00e9 basque, tenter sa chance. En vain. Au sommet, les favoris basculaient ensemble et temporisaient, favorisant le retour de&#8230; <strong>Marc Soler<\/strong> ! Ce dernier concluait les 15 derniers kilom\u00e8tres en solitaire. S&rsquo;offrant, au passage, une deuxi\u00e8me victoire cette saison apr\u00e8s le Trofeo Pollen\u00e7a-Andratx. Le deuxi\u00e8me succ\u00e8s \u00e9galement de la Movistar en 2020. Le Soler de la formation espagnole, c&rsquo;est Marc.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Marc Soler remporte la 2e \u00e9tape de <a href=\"https:\/\/twitter.com\/hashtag\/LaVuelta20?src=hash&amp;ref_src=twsrc%5Etfw\">#LaVuelta20<\/a> ! Primoz Roglic conforte son maillot rouge en allant prendre les 6 secondes de bonification de la deuxi\u00e8me place \u00e0 Lekunberri <a href=\"https:\/\/twitter.com\/hashtag\/LesRP?src=hash&amp;ref_src=twsrc%5Etfw\">#LesRP<\/a> <a href=\"https:\/\/t.co\/tWp09JX20e\">pic.twitter.com\/tWp09JX20e<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/1318943065344774144?ref_src=twsrc%5Etfw\">October 21, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Roglic capitalise<\/h2>\n<p style=\"text-align: justify;\">Sans \u00eatre vraiment en difficult\u00e9 ce mercredi, <strong>Primoz Roglic<\/strong> capitalise. Le Slov\u00e8ne de la Jumbo-Visma, deuxi\u00e8me derri\u00e8re Soler, a pris six secondes de bonification \u00e0 l&rsquo;arriv\u00e9e ce mercredi. Au g\u00e9n\u00e9ral, il devance d\u00e9sormais <strong>Dan Martin<\/strong> (Israel Start-Up Nation) de 9 secondes. Premier Fran\u00e7ais, <strong>Kenny Elissonde<\/strong> (Trek-Segafredo) est 17\u00e8me du g\u00e9n\u00e9ral, \u00e0 2&rsquo;13 du vainqueur sortant du Tour d&rsquo;Espagne.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-classement-2eme-etape\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tour d\u2019Espagne 2020 : le classement de la 2\u00e8me \u00e9tape<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-classement-general-maillot-rouge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tour d&rsquo;Espagne 2020 : le classement g\u00e9n\u00e9ral (maillot rouge)<\/a><\/strong><\/li>\n<\/ul>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOUR D&rsquo;ESPAGNE 2020 &#8211; En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri. Le vainqueur de Paris-Nice en 2018, qui a fait le boulot pour Alejandro Valverde et Enric Mas dans la derni\u00e8re difficult\u00e9 du jour, a devanc\u00e9 Primoz Roglic, qui a r\u00e9gl\u00e9 le groupe des cadors.<\/p>\n","protected":false},"author":4,"featured_media":83994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47042],"tags":[1671],"class_list":["post-83975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-tour-despagne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR D&#039;ESPAGNE 2020 - En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR D&#039;ESPAGNE 2020 - En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T15:48:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T17:42:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour d&rsquo;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape\",\"datePublished\":\"2020-10-21T15:48:02+00:00\",\"dateModified\":\"2020-10-21T17:42:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\"},\"wordCount\":433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png\",\"keywords\":[\"Tour d'Espagne\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\",\"name\":\"Tour d'Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png\",\"datePublished\":\"2020-10-21T15:48:02+00:00\",\"dateModified\":\"2020-10-21T17:42:22+00:00\",\"description\":\"TOUR D'ESPAGNE 2020 - En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png\",\"width\":800,\"height\":445,\"caption\":\"Marc Soler - Twitter La Vuelta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&rsquo;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape","description":"TOUR D'ESPAGNE 2020 - En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape","og_description":"TOUR D'ESPAGNE 2020 - En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2020-10-21T15:48:02+00:00","article_modified_time":"2020-10-21T17:42:22+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour d&rsquo;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape","datePublished":"2020-10-21T15:48:02+00:00","dateModified":"2020-10-21T17:42:22+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/"},"wordCount":433,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png","keywords":["Tour d'Espagne"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/","name":"Tour d'Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png","datePublished":"2020-10-21T15:48:02+00:00","dateModified":"2020-10-21T17:42:22+00:00","description":"TOUR D'ESPAGNE 2020 - En filou, Marc Soler (Movistar) a remport\u00e9 ce mercredi la 2\u00e8me \u00e9tape de la Vuelta 2020, \u00e0 Lekunberri.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Cyclisme-Tour-dEspagne-2020-Marc-Soler-triomphe-sur-la-2\u00e8me-\u00e9tape.png","width":800,"height":445,"caption":"Marc Soler - Twitter La Vuelta"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-d-espagne-2020-marc-soler-movistar-triomphe-sur-la-2eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&rsquo;Espagne 2020 : Marc Soler (Movistar) triomphe sur la 2\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/83975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=83975"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/83975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/83994"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=83975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=83975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=83975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}