{"id":8450,"date":"2017-12-11T19:08:50","date_gmt":"2017-12-11T18:08:50","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=8450"},"modified":"2017-12-11T20:58:01","modified_gmt":"2017-12-11T19:58:01","slug":"vestiaire-de-asccl-12-tonneins-leur-reussit-bien","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/","title":{"rendered":"Le vestiaire de l&rsquo;ASCCL #12 : Tonneins leur r\u00e9ussit bien"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\"><em>Retrouvez toutes les semaines \u00ab<span style=\"color: #000000;\">\u00a0<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/dicodusport.fr\/blog\/le-vestiaire-de-lasccl-toutes-les-semaines-sur-dicodusport-fr\/\">Le vestiaire de l&rsquo;ASCCL<\/a><\/span><\/span><\/em><\/span><em><span style=\"color: #000000;\">\u00a0\u00bb, la chronique qui vous\u00a0permettra de suivre la vie du club de football amateur de Castillonn\u00e8s. Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l&rsquo;<\/span><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/dicodusport.fr\/blog\/asccl\/\">ASCCL<\/a><\/span><span style=\"color: #000000;\">\u00a0qui\u00a0se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un\u00a0terrain qui leur r\u00e9ussit plut\u00f4t bien.<\/span><\/em><\/strong><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #000000; font-size: 20px;\"><strong><span style=\"color: #46da46;\">\u2752\u00a0<span style=\"color: #000000;\">L&rsquo;\u00e9quipe premi\u00e8re<\/span><\/span><\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\">Ce\u00a0samedi \u00e0 19h30, l&rsquo;ASCCL\u00a0\u00e9tait en d\u00e9placement \u00e0 Tonneins pour le compte de la 8\u00e8me journ\u00e9e de championnat.\u00a0Retour en d\u00e9tails sur la rencontre gr\u00e2ce \u00e0\u00a0Eric Prat.<span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">D\u00e9placement en terre tonneinquaise pour ce\u00a0premier match de la saison en nocturne. Dans ces\u00a0sept premi\u00e8res minutes, nous sommes bien en place et nous nous cr\u00e9ons une premi\u00e8re occasion par Arnaud Prat et un bon coup franc par Antoine Potet bien d\u00e9vi\u00e9 par le gardien. Notre jeu se met en\u00a0route et\u00a0aux 11\u00e8me et 12\u00e8me minutes,\u00a0deux\u00a0tirs d&rsquo;Arnaud Prat inqui\u00e8tent les cages adverses. Le pressing exerc\u00e9\u00a0par notre milieu : Lo\u00efc Campourcy, Pierrick Rispal et Thomas Heim fait son effet. Une premi\u00e8re mont\u00e9e de\u00a0Matthieu Billoir \u00e0 la 20\u00e8me suivi d&rsquo;un bon centre inqui\u00e9tera le gardien de Tonneins. A la demie heure de jeu, Simon Decroix remplace Ivo Moreira. Trois minutes plus tard,\u00a0un bon d\u00e9roul\u00e9 de\u00a0Matthieu sur la gauche trouve Arnaud\u00a0qui remet de la t\u00eate pour\u00a0Antoine Potet qui\u00a0voit sa reprise passer\u00a0au-dessus. En cette fin de mi-temps nous monopolisons le ballon puis arrive la 47\u00e8me minute, un bon renversement de jeu de Lo\u00efc Campourcy trouve Matthieu sur son c\u00f4t\u00e9 gauche. Il effectue un centre millim\u00e9tr\u00e9\u00a0en retrait et trouve Arnaud Prat qui, cette fois-ci, ajuste sa reprise et envoie le cuir au fond des filets (0-1). La mi-temps est siffl\u00e9e, nous avons domin\u00e9 les d\u00e9bats et respect\u00e9 les consignes du coach. Les tonneinquais n&rsquo;ont pas \u00e9t\u00e9 dangereux.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">D\u00e8s la reprise du second acte, un bon centre d&rsquo;Antoine trouve Simon Decroix au second poteau mais sa reprise est trop crois\u00e9e.\u00a0Trois minutes plus tard, sur un bon corner d&rsquo;Antoine Potet la t\u00eate d&rsquo;Arnaud Prat fr\u00f4lera la transversale. Notre jeu est bien plus f\u00e9brile qu&rsquo;en premi\u00e8re mi-temps, sans \u00eatre vraiment dangereux Tonneins ne l\u00e2che rien. Il faut attendre l&rsquo;heure de jeu pour voir Simon Decroix et Pierrick Rispal\u00a0\u00eatre tout pr\u00e8s d&rsquo;inscrire le 2\u00e8me but. Les occasions s&rsquo;encha\u00eenent mais sans r\u00e9ussite, attention \u00e0 la finition car nous n&rsquo;avons toujours que ce but d&rsquo;avance ! La 70\u00e8me voit Arnaud\u00a0buter sur le gardien. Notre d\u00e9fense compos\u00e9e de Hugo Prat, Tanguy Deschamps,\u00a0Matthieu Billoir\u00a0et Lucas Rouchaud reste attentive. A la 75\u00e8me,\u00a0Ivo Moreira remplace Antoine Potet.\u00a0Quelques instants plus tard, une belle tentative de lob de Simon Decroix \u00e9choue. On s&rsquo;approche de la fin du match et Arnaud Prat\u00a0voit son ballon sauver sur la ligne. Ce n&rsquo;est que partie remise\u00a0car dans les derni\u00e8res secondes,\u00a0\u00e0 la 96\u00e8me minute,\u00a0Matthieu Billoir, d\u00e9cid\u00e9ment tr\u00e8s en jambes sur ses mont\u00e9es, centre pour Arnaud Prat qui devance de la t\u00eate la sortie du gardien et assure cette victoire \u00e0 l&rsquo;ext\u00e9rieur (0-2).\u00a0\u00c0 signaler le bon premier match du jeune Lucas Rouchaud au poste de lat\u00e9ral droit.<\/span><\/p>\n<p><span class=\"tLFPmZaYosXJuWOMe5Q0zxAdCSKrfkEnVHc3Gij6Iwg1NT7qBhp4lUD8R\"><iframe loading=\"lazy\" title=\"Tonneins vs ASCCL (0-2) 8\u00e8me journ\u00e9e D1\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/kIDZbbuzSpI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"text-decoration: underline;\">Feuille de match<\/span> :<\/strong><\/p>\n<p style=\"text-align: justify;\">Championnat D1 &#8211; 09\/12\/2017 \u00e0 19h30<\/p>\n<h5 style=\"text-align: justify;\"><strong>Tonneins\u00a00 &#8211; 2\u00a0ASCCL<\/strong><\/h5>\n<p style=\"text-align: justify;\"><div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-caret su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Composition de l'equipe<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\"><span style=\"font-size: 16px;\">1.\u00a0Romain Bouyne<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 2.\u00a0Tanguy Deschamps<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 3. Matthieu Billoir<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 4.\u00a0Hugo Prat<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 5. Lo\u00efc Campourcy\u00a0\u00a9\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 6. Thomas Heim<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 7.\u00a0Pierrick Rispal<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 8. Lucas Rouchaud<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 9.\u00a0Arnaud Prat\u00a0\u26bd\u26bd<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 10. Antoine Potet<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 11.\u00a0Ivo Moreira\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 12. Boudjemaa Himmi<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 13. Simon Decroix<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 16px;\"> 14. Nuno\u00a0Moreira<\/span><\/p>\n<p style=\"text-align: justify;\">Entra\u00eeneur\u00a0: Manu Pacher<\/div><\/div>\n<h4 style=\"text-align: justify;\"><span style=\"font-size: 20px;\"><strong><span style=\"color: #000000;\"><span style=\"color: #46da46;\">\u2752<span style=\"color: #000000;\">\u00a0Le mot du coach<\/span><\/span><\/span><\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\">Cette victoire nous permet de rester au contact. Tout n&rsquo;a pas \u00e9t\u00e9 parfait mais j&rsquo;ai aim\u00e9 le s\u00e9rieux et l&rsquo;abn\u00e9gation de mon \u00e9quipe. Cette victoire sera valoris\u00e9e si on ne perd pas contre Gontaud. On va bien pr\u00e9parer le match, afin de le gagner.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"font-size: 20px;\"><strong><span style=\"color: #000000;\"><span style=\"color: #46da46;\">\u2752<span style=\"color: #000000;\">\u00a0L&rsquo;analyse du milieu de terrain\u00a0:\u00a0Pierrick Rispal<\/span><\/span><\/span><\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\">La victoire \u00e9tait imp\u00e9rative suite \u00e0 la d\u00e9convenue du week-end pr\u00e9c\u00e9dent face \u00e0 Colayrac. Nous effectuons une tr\u00e8s bonne premi\u00e8re mi-temps dans l&rsquo;intensit\u00e9 et dans l&rsquo;envie, sans occasion conc\u00e9d\u00e9e, r\u00e9compens\u00e9e par un but juste avant la pause. M\u00e9connaissables en seconde mi-temps (stress ?), sans r\u00e9ussite devant le but, le sc\u00e9nario se termine bien par un but en toute fin de match. C&rsquo;est un tr\u00e8s bon r\u00e9sultat, sans but ni r\u00e9elle occasion conc\u00e9d\u00e9e. Peut \u00eatre qu&rsquo;avec plus de r\u00e9ussite devant, le match aurait \u00e9t\u00e9 plus facile. Concentrons-nous sur Gontaud, une victoire et on sera au chaud pour l&rsquo;hiver.<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"font-size: 20px;\"><strong><span style=\"color: #000000;\"><span style=\"color: #46da46;\">\u2752<\/span>\u00a0Prochain match<\/span><\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Les joueurs de Castillonn\u00e8s\u00a0recevront Gontaud en championnat dimanche prochain\u00a0(17 d\u00e9cembre \u00e0 15h). Une rencontre qui pr\u00e9c\u00e9dera la tr\u00eave hivernale, les joueurs voudront finir l&rsquo;ann\u00e9e sur une bonne note.<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"color: #000000;\"><strong>ASCCL<\/strong><\/span><\/em><em><br \/>\n<\/em><a href=\"http:\/\/asccl.footeo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4941\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/09\/logo-site-web-150x150.png\" alt=\"\" width=\"35\" height=\"35\" \/><\/a><a href=\"http:\/\/asccl.footeo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5480\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/10\/logo-site-web-150x150.png\" alt=\"\" width=\"39\" height=\"39\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/10\/logo-site-web-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/10\/logo-site-web-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/10\/logo-site-web-768x768.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/10\/logo-site-web.png 800w\" sizes=\"auto, (max-width: 39px) 100vw, 39px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retrouvez toutes les semaines \u00ab\u00a0Le vestiaire de l&rsquo;ASCCL\u00a0\u00bb, la chronique qui vous\u00a0permettra de suivre la vie du club de football amateur de Castillonn\u00e8s. Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l&rsquo;ASCCL\u00a0qui\u00a0se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un\u00a0terrain qui leur r\u00e9ussit plut\u00f4t bien. \u2752\u00a0L&rsquo;\u00e9quipe premi\u00e8re Ce\u00a0samedi \u00e0 19h30, l&rsquo;ASCCL\u00a0\u00e9tait en d\u00e9placement \u00e0 Tonneins pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8473,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301,2016],"tags":[1875,1877,1876,1799,1880,75,1878,2017],"class_list":["post-8450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-nos-champions","tag-asccl","tag-cahuzac","tag-castillonnes","tag-championnat","tag-d1","tag-football","tag-lalandusse","tag-le-vestiaire-de-lasccl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le vestiaire de l&#039;ASCCL #12 : Tonneins leur r\u00e9ussit bien<\/title>\n<meta name=\"description\" content=\"Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l&#039;ASCCL qui se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un terrain qui leur r\u00e9ussit plut\u00f4t bien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le vestiaire de l&#039;ASCCL #12 : Tonneins leur r\u00e9ussit bien\" \/>\n<meta property=\"og:description\" content=\"Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l&#039;ASCCL qui se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un terrain qui leur r\u00e9ussit plut\u00f4t bien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-11T18:08:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-11T19:58:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Le vestiaire de l&rsquo;ASCCL #12 : Tonneins leur r\u00e9ussit bien\",\"datePublished\":\"2017-12-11T18:08:50+00:00\",\"dateModified\":\"2017-12-11T19:58:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\"},\"wordCount\":856,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png\",\"keywords\":[\"ASCCL\",\"Cahuzac\",\"Castillonn\u00e8s\",\"championnat\",\"D1\",\"Football\",\"Lalandusse\",\"Le vestiaire de l'ASCCL\"],\"articleSection\":[\"Football\",\"Nos champions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#respond\"]}],\"copyrightYear\":\"2017\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\",\"name\":\"Le vestiaire de l'ASCCL #12 : Tonneins leur r\u00e9ussit bien\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png\",\"datePublished\":\"2017-12-11T18:08:50+00:00\",\"dateModified\":\"2017-12-11T19:58:01+00:00\",\"description\":\"Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l'ASCCL qui se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un terrain qui leur r\u00e9ussit plut\u00f4t bien.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png\",\"width\":1200,\"height\":670,\"caption\":\"Le vestiaire de l'ASCCL #12 Tonneins leur r\u00e9ussit bien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le vestiaire de l&rsquo;ASCCL #12 : Tonneins leur r\u00e9ussit bien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le vestiaire de l'ASCCL #12 : Tonneins leur r\u00e9ussit bien","description":"Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l'ASCCL qui se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un terrain qui leur r\u00e9ussit plut\u00f4t bien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/","og_locale":"fr_FR","og_type":"article","og_title":"Le vestiaire de l'ASCCL #12 : Tonneins leur r\u00e9ussit bien","og_description":"Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l'ASCCL qui se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un terrain qui leur r\u00e9ussit plut\u00f4t bien.","og_url":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2017-12-11T18:08:50+00:00","article_modified_time":"2017-12-11T19:58:01+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Le vestiaire de l&rsquo;ASCCL #12 : Tonneins leur r\u00e9ussit bien","datePublished":"2017-12-11T18:08:50+00:00","dateModified":"2017-12-11T19:58:01+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/"},"wordCount":856,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png","keywords":["ASCCL","Cahuzac","Castillonn\u00e8s","championnat","D1","Football","Lalandusse","Le vestiaire de l'ASCCL"],"articleSection":["Football","Nos champions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#respond"]}],"copyrightYear":"2017","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/","url":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/","name":"Le vestiaire de l'ASCCL #12 : Tonneins leur r\u00e9ussit bien","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png","datePublished":"2017-12-11T18:08:50+00:00","dateModified":"2017-12-11T19:58:01+00:00","description":"Dans le douzi\u00e8me \u00e9pisode, retour sur le match de l'ASCCL qui se d\u00e9pla\u00e7ait \u00e0 Tonneins en championnat, un terrain qui leur r\u00e9ussit plut\u00f4t bien.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/12\/Le-vestiaire-de-lASCCL-12-Tonneins-leur-r\u00e9ussit-bien.png","width":1200,"height":670,"caption":"Le vestiaire de l'ASCCL #12 Tonneins leur r\u00e9ussit bien"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/vestiaire-de-asccl-12-tonneins-leur-reussit-bien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le vestiaire de l&rsquo;ASCCL #12 : Tonneins leur r\u00e9ussit bien"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/8450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=8450"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/8450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/8473"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=8450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=8450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=8450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}