{"id":84775,"date":"2020-10-24T23:00:59","date_gmt":"2020-10-24T21:00:59","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=84775&#038;preview=true&#038;preview_id=84775"},"modified":"2021-10-18T17:20:09","modified_gmt":"2021-10-18T15:20:09","slug":"la-france-redemarre-avec-un-succes-face-au-pays-de-galles","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/","title":{"rendered":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TEST MATCH &#8211; Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition (38-21).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Un Stade de France qui sonne creux et des Bleus qui ne rentrent pas bien dans le match, \u00e0 l\u2019image de <strong>Gregory Alldritt<\/strong> qui laisse tomber le ballon d\u00e8s le coup d\u2019envoi. Les Gallois n\u2019en demandaient pas tant, <strong>Halfpenny<\/strong> est trouv\u00e9 en bout de ligne et aplatit d\u00e8s la premi\u00e8re minute. Avec la transformation puis une p\u00e9nalit\u00e9 de <strong>Dan Biggar<\/strong>, le Pays de Galles m\u00e8ne 10 \u00e0 0.<\/p>\n<p style=\"text-align: justify;\">Le <strong>XV de France<\/strong> fait une premi\u00e8re demi-heure catastrophique mais fait finalement preuve de r\u00e9alisme, puisqu&rsquo;il marque sur sa seule occasion. Baille conclut apr\u00e8s une p\u00e9nalit\u00e9 jou\u00e9e vite par <strong>Ga\u00ebl Fickou<\/strong>, suite \u00e0 une belle perc\u00e9e de <strong>Romain Ntamack<\/strong>. Mais la v\u00e9rit\u00e9, c\u2019est que les hommes de <strong>Galthi\u00e9<\/strong> sont \u00e0 c\u00f4t\u00e9 de leurs pompes dans les choix \u00e0 faire, et sont compl\u00e8tement domin\u00e9s dans le combat au sol.<\/p>\n<h2 style=\"text-align: justify;\">Vakatawa et Dupont en feu<\/h2>\n<p style=\"text-align: justify;\">Heureusement pour les Tricolores, les Gallois sont autant pr\u00e9sents dans le combat que sans id\u00e9e dans le jeu. Une fois l\u2019orage pass\u00e9, <strong>Dupont<\/strong> s\u2019offre un doubl\u00e9 en quelques minutes (31&prime; et 34&prime;) dans une d\u00e9fense du XV du Poireau qui prend l\u2019eau. <strong>Virimi Vakatawa<\/strong> est primordial sur les deux essais : parfait au relais sur le premier avec une merveille d&rsquo;offload avant de casser la ligne sur le second : 21-13. C\u2019est finalement sur ce score que les deux \u00e9quipes rentrent aux vestiaires. Flatteur pour les Bleus, tant les 30 premi\u00e8res minutes ont \u00e9t\u00e9 d\u00e9licates.<\/p>\n<p style=\"text-align: justify;\">Comme en d\u00e9but de match, les Fran\u00e7ais ratent un peu leur entame et se mettent rapidement \u00e0 la faute. <strong>Biggar<\/strong> prend les points mais c\u2019est ensuite le sch\u00e9ma inverse et <strong>Ntamack<\/strong> passe aussi la p\u00e9nalit\u00e9, 24-16. Les deux entra\u00eeneurs commencent la revue d\u2019effectif alors que les impr\u00e9cisions et les fautes se multiplient dans un match qui a perdu en intensit\u00e9. <strong>Biggar<\/strong> doit faire face \u00e0 son premier \u00e9chec \u00e0 l\u2019heure de jeu alors qu\u2019il tentait d\u2019ajouter trois points.<\/p>\n<h2 style=\"text-align: justify;\">Les Bleus avec s\u00e9rieux<\/h2>\n<p style=\"text-align: justify;\"><strong>Biggar<\/strong> ne parvient pas \u00e0 r\u00e9gler la mire et rate une deuxi\u00e8me p\u00e9nalit\u00e9 de suite. Les Bleus ne s\u2019\u00e9taient pas montr\u00e9s dangereux depuis de longues minutes mais Dupont n\u2019a besoin que d\u2019un petit trou pour envoyer <strong>Captain Ollivon<\/strong> \u00e0 l\u2019essai. Avec la nouvelle transformation du buteur fran\u00e7ais, le break est fait, 31-16.<\/p>\n<p style=\"text-align: justify;\">Les Gallois ne sont pas r\u00e9sign\u00e9s, <strong>Lewis<\/strong> conclut un temps fort pour maintenir un peu de suspense dans cette fin de rencontre. Mais ce sont bien les Bleus qui ont le dernier mot avec un essai de <strong>Teddy Thomas<\/strong> qui tape pour lui-m\u00eame et marque en coin. Avec le dernier coup de pied r\u00e9ussi par <strong>Ntamack<\/strong>, la France s\u2019impose 38 \u00e0 21 face au Pays de Galles pour son retour \u00e0 la comp\u00e9tition.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u0300 ! Les Bleus s&rsquo;imposent ce soir au <a href=\"https:\/\/twitter.com\/StadeFrance?ref_src=twsrc%5Etfw\">@StadeFrance<\/a> avec 5 essais inscrits ! Un tr\u00e8s bon match avant de recevoir l&rsquo;Irlande la semaine prochaine pour terminer le <a href=\"https:\/\/twitter.com\/hashtag\/SixNations?src=hash&amp;ref_src=twsrc%5Etfw\">#SixNations<\/a> 2020 ! <a href=\"https:\/\/twitter.com\/hashtag\/FRAGAL?src=hash&amp;ref_src=twsrc%5Etfw\">#FRAGAL<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/XVdeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#XVdeFrance<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/NeFaisonsXV?src=hash&amp;ref_src=twsrc%5Etfw\">#NeFaisonsXV<\/a> <a href=\"https:\/\/t.co\/deRp12cc9J\">pic.twitter.com\/deRp12cc9J<\/a><\/p>\n<p>\u2014 France Rugby (@FranceRugby) <a href=\"https:\/\/twitter.com\/FranceRugby\/status\/1320106196020482056?ref_src=twsrc%5Etfw\">October 24, 2020<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/rugby-xv-de-france-notes-bleus-face-pays-de-galles\/\" target=\"_blank\" rel=\"noopener noreferrer\">XV de France : les notes des Bleus face au Pays de Galles<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<\/em><\/strong><br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TEST MATCH &#8211; Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition (38-21).<\/p>\n","protected":false},"author":1,"featured_media":84782,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,19951],"tags":[523,338,1638],"class_list":["post-84775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-bleus","tag-pays-de-galles","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-24T21:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T15:20:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles\",\"datePublished\":\"2020-10-24T21:00:59+00:00\",\"dateModified\":\"2021-10-18T15:20:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png\",\"keywords\":[\"bleus\",\"Pays De Galles\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/\",\"name\":\"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png\",\"datePublished\":\"2020-10-24T21:00:59+00:00\",\"dateModified\":\"2021-10-18T15:20:09+00:00\",\"description\":\"Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles","description":"Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/","og_locale":"fr_FR","og_type":"article","og_title":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles","og_description":"Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition.","og_url":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-10-24T21:00:59+00:00","article_modified_time":"2021-10-18T15:20:09+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles","datePublished":"2020-10-24T21:00:59+00:00","dateModified":"2021-10-18T15:20:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png","keywords":["bleus","Pays De Galles","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/","url":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/","name":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png","datePublished":"2020-10-24T21:00:59+00:00","dateModified":"2021-10-18T15:20:09+00:00","description":"Apr\u00e8s une entame compliqu\u00e9e, le XV de France a \u00e9t\u00e9 r\u00e9aliste offensivement pour dominer le Pays de Galles pour son retour \u00e0 la comp\u00e9tition.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/10\/Rugby-La-France-domine-largement-le-Pays-de-Galles.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/la-france-redemarre-avec-un-succes-face-au-pays-de-galles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"La France red\u00e9marre avec un succ\u00e8s face au Pays de Galles"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/84775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=84775"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/84775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/84782"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=84775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=84775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=84775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}