{"id":87563,"date":"2020-11-11T19:35:49","date_gmt":"2020-11-11T18:35:49","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=87563"},"modified":"2020-11-11T23:33:45","modified_gmt":"2020-11-11T22:33:45","slug":"droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/","title":{"rendered":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>La prochaine Autumn Nations Cup sera retransmise au Royaume-Uni sur la plateforme de streaming Amazon Prime Video. 13 matchs seront diffus\u00e9s en direct sur celle-ci. Est-ce le d\u00e9but d&rsquo;une nouvelle \u00e8re dans la diffusion des matchs de rugby ?\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Ce week-end marque le d\u00e9but d&rsquo;une nouvelle comp\u00e9tition, l&rsquo;<a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/autumn-nations-cup-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Autumn Nations Cup<\/strong><\/a>. Elle remplace l&rsquo;habituelle tourn\u00e9e d&rsquo;automne o\u00f9 s&rsquo;affrontaient habituellement les nations des h\u00e9misph\u00e8res Nord et Sud. \u00c0 cause de la pand\u00e9mie de la Covid-19, ce seront principalement les s\u00e9lections du Tournoi des Six Nations qui s&rsquo;affronteront. Rejointes par la G\u00e9orgie et les Fidji. Amazon a acquis la diffusion de l&rsquo;int\u00e9gralit\u00e9 des rencontres, des match de phase de poules jusqu&rsquo;aux finales.<\/p>\n<p style=\"text-align: justify;\">Ainsi, 13 rencontres seront diffus\u00e9es sur Prime Video. Les fans de rugby du Royaume-Uni devront donc s&rsquo;abonner \u00e0 ce service pour suivre la comp\u00e9tition. En Irlande, les trois rencontres seront diffus\u00e9es par Channel 4 tandis que chez nous, en France, c&rsquo;est le service public et France T\u00e9l\u00e9visions qui diffusera les rencontres du <strong>XV de France<\/strong>, sur France 2. Dans une ann\u00e9e \u00e9trange et difficile pour le rugby, l&rsquo;arriv\u00e9e d&rsquo;Amazon dans la sph\u00e8re rugbystique marque-t-elle le d\u00e9but d&rsquo;une grande r\u00e9volution \u00e0 venir ?<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Be thankful these lads are only delivering rugby &#x1f4e6;&#x274c;<\/p>\n<p>8&#xfe0f;&#x20e3; teams, 4&#xfe0f;&#x20e3; weekends, 1&#xfe0f;&#x20e3; winner <a href=\"https:\/\/twitter.com\/hashtag\/AmazonDeliversTheRugby?src=hash&amp;ref_src=twsrc%5Etfw\">#AmazonDeliversTheRugby<\/a> LIVE on <a href=\"https:\/\/twitter.com\/hashtag\/PrimeVideo?src=hash&amp;ref_src=twsrc%5Etfw\">#PrimeVideo<\/a> &#x1f3c9; <a href=\"https:\/\/t.co\/aEyznDkUQC\">pic.twitter.com\/aEyznDkUQC<\/a><\/p>\n<p>\u2014 Amazon Prime Video Sport (@primevideosport) <a href=\"https:\/\/twitter.com\/primevideosport\/status\/1326231902060126208?ref_src=twsrc%5Etfw\">November 10, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le Six Nations, voire la Premiership, prochaines cibles de Prime Video<\/h2>\n<p style=\"text-align: justify;\">La relation entre <strong>Amazon<\/strong> et <strong>Six Nations Rugby Limited<\/strong>, qui organise chaque ann\u00e9e le <strong>Tournoi des 6 Nations<\/strong>, a d\u00e9j\u00e0 commenc\u00e9 lors de la diffusion de la Coupe des Nations d&rsquo;Automne. Ce partenariat entre ces deux entit\u00e9s a relanc\u00e9 le d\u00e9bat sur la sortie ou non du Six Nations de la t\u00e9l\u00e9vision gratuite. Au Royaume Uni, ce sont deux cha\u00eenes de t\u00e9l\u00e9vision britanniques qui se chargent de la diffusion des rencontres : <strong>BBC<\/strong> et <strong>ITV<\/strong>. L&rsquo;accord de droits pour ces deux cha\u00eenes se termine \u00e0 l&rsquo;issue du prochain Tournoi, en 2021 donc, et on peut penser qu&rsquo;Amazon va tenter de s&rsquo;immiscer dans la discussion.<\/p>\n<p style=\"text-align: justify;\">Au d\u00e9but de l&rsquo;ann\u00e9e, le fonds d&rsquo;investissement <strong>CVC<\/strong> voulait investir 300 millions de livres dans le tournoi des Six Nations, pour une participation \u00e0 hauteur de 14%. Cependant, la crise pand\u00e9mique a interrompu ces n\u00e9gociations. Mais CVC, \u00e7a ne vous dit rien ? Ce fonds d&rsquo;investissement d\u00e9tient en effet 27% de la Premiership, le championnat de rugby anglais. Depuis plusieurs mois, des rumeurs affirment que l&rsquo;\u00e9lite du rugby d&rsquo;Outre-Manche voudrait que ses rencontres soient diffus\u00e9es sur une seule et m\u00eame cha\u00eene d\u00e9di\u00e9e au rugby. Actuellement, le diffuseur principal de la comp\u00e9tition est BT Sports, et ce depuis l&rsquo;ann\u00e9e 2013-2014.<\/p>\n<p style=\"text-align: justify;\">Ainsi, chaque ann\u00e9e, BT Sports verse 40 millions de livres \u00e0 la <strong>Premiership Rugby<\/strong> pour retransmettre l&rsquo;ensemble de la comp\u00e9tition. N\u00e9anmoins, le contrat entre BT Sports et la Premiership prend fin \u00e0 la fin de la saison 2020-2021. C&rsquo;est le produit phare de la cha\u00eene, m\u00eame si entre temps, elle a \u00e9galement acquis des droits sur la diffusion des matchs de la Premier League anglaise en football.<\/p>\n<p style=\"text-align: justify;\">Premiership Rugby et BT Sports sont d\u00e9sormais en pourparlers pour prolonger le contrat au-del\u00e0 de la prochaine saison de championnat. Cependant, BT Sports souhaite revoir le contrat \u00e0 la baisse, en raison de l&rsquo;impact du Covid-19. De ce fait, <strong>Premiership Rugby<\/strong> pourrait d\u00e9cider d&rsquo;ouvrir la porte \u00e0 de nouveaux concurrents, dont Amazon.<\/p>\n<h2 style=\"text-align: justify;\">Amazon s&rsquo;attaque \u00e0 tous les march\u00e9s<\/h2>\n<p style=\"text-align: justify;\">Rappelons que durant cette crise pand\u00e9mique, <strong>Amazon est une des rares entreprises ayant d\u00e9velopp\u00e9 sa croissance \u00e0 vitesse grand V<\/strong>. Les chiffres sont stratosph\u00e9riques : au deuxi\u00e8me trimestre 2020, le groupe a g\u00e9n\u00e9r\u00e9 un chiffre d&rsquo;affaires de 75 milliards d&rsquo;euros, en hausse de 40% sur un an. Avec des chiffres d&rsquo;affaires de la sorte, nul doute que le groupe, qui veut d\u00e9velopper sa plateforme de streaming via l&rsquo;acquisition de droits TV sportifs, fait peur \u00e0 beaucoup de diffuseurs.<\/p>\n<p style=\"text-align: justify;\">Les premiers faits d&rsquo;armes de cette plateforme ont s\u00e9vi sur le tennis, avec notamment la diffusion des <strong>Masters 500 et 1000<\/strong>, diffus\u00e9s au Royaume-Uni et en Irlande jusqu&rsquo;en 2023, et ce au nez et \u00e0 la barbe de Sky Sports. Apr\u00e8s \u00e7a, Amazon a \u00e9galement prolong\u00e9 son engagement pour la diffusion de l&rsquo;<strong>US Open<\/strong> sur les cinq prochaines ann\u00e9es. En avril dernier, le groupe avait \u00e9galement annonc\u00e9 la diffusion de quatre matchs de Premier League anglaise en direct, en partenariat avec Twitch.<\/p>\n<p style=\"text-align: justify;\">Et pour l&rsquo;avenir ? Les <strong>droits TV de Roland-Garros<\/strong> seront partag\u00e9s entre France TV et Amazon, et ce pour les \u00e9ditions 2021, 2022 et 2023. <strong>Prime Video<\/strong> diffusera ainsi en exclusivit\u00e9 les rencontres programm\u00e9es sur le court Simonne-Mathieu.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">De moins en moins de sport gratuit \u00e0 la TV<br \/>\nRolland Garros passe sur Amazon<\/p>\n<p>En 2021, il faudra payer pour voir une partie des matchs de Roland-Garros sur Amazon Prime Video<a href=\"https:\/\/t.co\/j2SFDXkluB\">https:\/\/t.co\/j2SFDXkluB<\/a><\/p>\n<p>\u2014 Guillaume Lopez (@Guillau74150605) <a href=\"https:\/\/twitter.com\/Guillau74150605\/status\/1316092308551593987?ref_src=twsrc%5Etfw\">October 13, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Amazon a \u00e9galement acquis des droits sur la Ligue des Champions en Allemagne. Ainsi, l&rsquo;un des matchs phares de la grande Coupe d&rsquo;Europe pour la soir\u00e9e du mardi sera retransmis en exclusivit\u00e9 sur Prime Video. Avec une telle puissance financi\u00e8re, il est clair que Amazon via sa plateforme de streaming <strong>Prime Video<\/strong> deviendra un acteur majeur de la diffusion sportive. Et ce dans le monde entier. Pour l&rsquo;<strong>Autumn Nations Cup<\/strong>, la cha\u00eene s&rsquo;est pay\u00e9e le luxe de d\u00e9baucher des consultanrs de renom tels que <strong>Bryan Habana<\/strong>, <strong>Serge Betsen<\/strong>, <strong>David Flatman<\/strong> ou encore <strong>Sam Warburton<\/strong>. Si cette comp\u00e9tition est une r\u00e9ussite, nul doute que le groupe s&rsquo;attaquera \u00e0 d&rsquo;autres march\u00e9s.<\/p>\n<p><em><strong>Nicolas Mezine<br \/>\n<a href=\"https:\/\/twitter.com\/Lbiji13?\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prochaine Autumn Nations Cup sera retransmise au Royaume-Uni sur la plateforme de streaming Amazon Prime Video. 13 matchs seront diffus\u00e9s en direct sur celle-ci. Est-ce le d\u00e9but d&rsquo;une nouvelle \u00e8re dans la diffusion des matchs de rugby ?\u00a0<\/p>\n","protected":false},"author":42,"featured_media":87642,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8451],"tags":[11639,9635,159,1463],"class_list":["post-87563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medias","tag-autumn-nations-cup","tag-droits-tv","tag-roland-garros","tag-us-open"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?<\/title>\n<meta name=\"description\" content=\"Le g\u00e9ant am\u00e9ricain de la vente en ligne, Amazon, est pr\u00eat \u00e0 devenir un acteur majeur de la diffusion lors des prochaines ann\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?\" \/>\n<meta property=\"og:description\" content=\"Le g\u00e9ant am\u00e9ricain de la vente en ligne, Amazon, est pr\u00eat \u00e0 devenir un acteur majeur de la diffusion lors des prochaines ann\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T18:35:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-11T22:33:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?\",\"datePublished\":\"2020-11-11T18:35:49+00:00\",\"dateModified\":\"2020-11-11T22:33:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\"},\"wordCount\":1009,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png\",\"keywords\":[\"Autumn Nations Cup\",\"Droits TV\",\"Roland-Garros\",\"US Open\"],\"articleSection\":[\"M\u00e9dias\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\",\"name\":\"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png\",\"datePublished\":\"2020-11-11T18:35:49+00:00\",\"dateModified\":\"2020-11-11T22:33:45+00:00\",\"description\":\"Le g\u00e9ant am\u00e9ricain de la vente en ligne, Amazon, est pr\u00eat \u00e0 devenir un acteur majeur de la diffusion lors des prochaines ann\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png\",\"width\":800,\"height\":445,\"caption\":\"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?","description":"Le g\u00e9ant am\u00e9ricain de la vente en ligne, Amazon, est pr\u00eat \u00e0 devenir un acteur majeur de la diffusion lors des prochaines ann\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/","og_locale":"fr_FR","og_type":"article","og_title":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?","og_description":"Le g\u00e9ant am\u00e9ricain de la vente en ligne, Amazon, est pr\u00eat \u00e0 devenir un acteur majeur de la diffusion lors des prochaines ann\u00e9es.","og_url":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-11-11T18:35:49+00:00","article_modified_time":"2020-11-11T22:33:45+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png","type":"image\/png"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?","datePublished":"2020-11-11T18:35:49+00:00","dateModified":"2020-11-11T22:33:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/"},"wordCount":1009,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png","keywords":["Autumn Nations Cup","Droits TV","Roland-Garros","US Open"],"articleSection":["M\u00e9dias"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/","url":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/","name":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png","datePublished":"2020-11-11T18:35:49+00:00","dateModified":"2020-11-11T22:33:45+00:00","description":"Le g\u00e9ant am\u00e9ricain de la vente en ligne, Amazon, est pr\u00eat \u00e0 devenir un acteur majeur de la diffusion lors des prochaines ann\u00e9es.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Droits-TV-Amazon-Prime-Video-pr\u00eat-\u00e0-redistribuer-les-cartes.png","width":800,"height":445,"caption":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/droits-tv-amazon-prime-video-pret-a-redistribuer-les-cartes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Droits TV : Amazon Prime Video pr\u00eat \u00e0 redistribuer les cartes ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/87563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=87563"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/87563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/87642"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=87563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=87563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=87563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}