{"id":87819,"date":"2020-11-13T17:54:39","date_gmt":"2020-11-13T16:54:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=87819&#038;preview=true&#038;preview_id=87819"},"modified":"2021-10-18T16:40:57","modified_gmt":"2021-10-18T14:40:57","slug":"xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/","title":{"rendered":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&rsquo;\u00c9cosse"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/tag\/xv-de-france\/\" target=\"_blank\" rel=\"noopener noreferrer\">XV DE FRANCE<\/a> &#8211; Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match d&rsquo;<a href=\"https:\/\/dicodusport.fr\/blog\/autumn-nations-cup-2020-calendrier-resultats-classement\/\" target=\"_blank\" rel=\"noopener noreferrer\">Autumn Nations Cup<\/a> face \u00e0 l&rsquo;\u00c9cosse pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">En raison de l&rsquo;annulation du match face aux Fidji pr\u00e9vu ce dimanche, Fabien Galthi\u00e9 a d\u00e9cid\u00e9 de rappeler une grande partie du groupe convoqu\u00e9 face aux Flying Fijians. Le Girondin <strong>Matthieu Jalibert<\/strong> est de retour, tout comme <strong>Alivereti Raka<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3f4;&#xe0067;&#xe0062;&#xe0073;&#xe0063;&#xe0074;&#xe007f;&#x1f1eb;&#x1f1f7; <a href=\"https:\/\/twitter.com\/FGalthie?ref_src=twsrc%5Etfw\">@FGalthie<\/a> a annonc\u00e9 la liste des 31 joueurs convoqu\u00e9s pour pr\u00e9parer le match contre l&rsquo;\u00c9cosse \u00e0 Murrayfield le dimanche 22 novembre prochain. <a href=\"https:\/\/twitter.com\/hashtag\/ECOFRA?src=hash&amp;ref_src=twsrc%5Etfw\">#ECOFRA<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/XVdeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#XVdeFrance<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/NeFaisonsXV?src=hash&amp;ref_src=twsrc%5Etfw\">#NeFaisonsXV<\/a><\/p>\n<p>\u2014 France Rugby (@FranceRugby) <a href=\"https:\/\/twitter.com\/FranceRugby\/status\/1327288296364503041?ref_src=twsrc%5Etfw\">November 13, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV DE FRANCE &#8211; Ce jeudi soir, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l&rsquo;\u00c9cosse pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.<\/p>\n","protected":false},"author":1,"featured_media":104421,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,19951],"tags":[11639,1332,7515,7725,1638],"class_list":["post-87819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-autumn-nations-cup","tag-ecosse","tag-fabien-galthie","tag-liste-xv-de-france","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XV de France : la liste de 31 joueurs pour pr\u00e9parer l&#039;\u00c9cosse<\/title>\n<meta name=\"description\" content=\"XV DE FRANCE - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l&#039;\u00c9cosse, pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&#039;\u00c9cosse\" \/>\n<meta property=\"og:description\" content=\"XV DE FRANCE - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l&#039;\u00c9cosse, pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-13T16:54:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T14:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&#039;\u00c9cosse\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&rsquo;\u00c9cosse\",\"datePublished\":\"2020-11-13T16:54:39+00:00\",\"dateModified\":\"2021-10-18T14:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/\"},\"wordCount\":131,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png\",\"keywords\":[\"Autumn Nations Cup\",\"Ecosse\",\"Fabien Galthi\u00e9\",\"Liste XV de France\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/\",\"name\":\"XV de France : la liste de 31 joueurs pour pr\u00e9parer l'\u00c9cosse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png\",\"datePublished\":\"2020-11-13T16:54:39+00:00\",\"dateModified\":\"2021-10-18T14:40:57+00:00\",\"description\":\"XV DE FRANCE - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l'\u00c9cosse, pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png\",\"width\":800,\"height\":445,\"caption\":\"Coupe du monde de rugby 2023 : le calendrier du XV de France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&rsquo;\u00c9cosse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l'\u00c9cosse","description":"XV DE FRANCE - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l'\u00c9cosse, pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l'\u00c9cosse","og_description":"XV DE FRANCE - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l'\u00c9cosse, pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-11-13T16:54:39+00:00","article_modified_time":"2021-10-18T14:40:57+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l'\u00c9cosse","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&rsquo;\u00c9cosse","datePublished":"2020-11-13T16:54:39+00:00","dateModified":"2021-10-18T14:40:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/"},"wordCount":131,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png","keywords":["Autumn Nations Cup","Ecosse","Fabien Galthi\u00e9","Liste XV de France","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/","name":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l'\u00c9cosse","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png","datePublished":"2020-11-13T16:54:39+00:00","dateModified":"2021-10-18T14:40:57+00:00","description":"XV DE FRANCE - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 une liste de 31 joueurs pour pr\u00e9parer le match face \u00e0 l'\u00c9cosse, pr\u00e9vu le 22 novembre prochain, \u00e0 Murrayfield.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/02\/Bleus-Les-notes-du-XV-de-France-face-a-lItalie.png","width":800,"height":445,"caption":"Coupe du monde de rugby 2023 : le calendrier du XV de France"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-de-31-joueurs-pour-preparer-l-ecosse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : la liste de 31 joueurs pour pr\u00e9parer l&rsquo;\u00c9cosse"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/87819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=87819"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/87819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/104421"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=87819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=87819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=87819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}