{"id":88738,"date":"2020-11-19T02:13:13","date_gmt":"2020-11-19T01:13:13","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=88738"},"modified":"2020-11-19T02:14:13","modified_gmt":"2020-11-19T01:14:13","slug":"draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/","title":{"rendered":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs. Dans un format visioconf\u00e9rence in\u00e9dit, la Draft 2020 a enfin livr\u00e9 son verdict et c&rsquo;est le jeune arri\u00e8re de 19 ans qui restera dans la post\u00e9rit\u00e9 comme le premier joueur de cette Draft.\u00a0<\/em> <\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c0 la lutte avec LaMelo Ball dans la plupart des Mock Draft, c&rsquo;est finalement Anthony Edwards qui a \u00e9t\u00e9 choisi par les Minnesota Timberwolves. Sa future compl\u00e9mentarit\u00e9 avec D&rsquo;Angelo Russell est sans doute ce qui a convaincu Gersson Rosas et le management des Wolves de pr\u00e9f\u00e9rer Edwards au cadet des fr\u00e8res Ball. De par son profil athl\u00e9tique (1 m\u00e8tre 97 pour 101 kilos), l&rsquo;arri\u00e8re sait allier puissance et agilit\u00e9, tant en attaque qu&rsquo;en d\u00e9fense. Son principal d\u00e9faut reste sa pr\u00e9cision au tir, un aspect de son jeu qui sera \u00e0 am\u00e9liorer pour vraiment justifier son statut de choix n\u00b01 de la Draft.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est d&rsquo;ailleurs le premier joueur de l&rsquo;universit\u00e9 de Georgia \u00e0 \u00eatre s\u00e9lectionn\u00e9 \u00e0 cette position, le record \u00e9tait d\u00e9tenu par Dominique Wilkins qui avait \u00e9t\u00e9 s\u00e9lectionn\u00e9 en n\u00b03 de la Draft 1982. On ne compte n\u00e9anmoins que quelques rares joueurs issus de cette universit\u00e9 \u00e0 avoir \u00e9volu\u00e9 \u00e0 un bon niveau en NBA, parmi lesquels Kentavious Caldwell-Pope (2013, choix 8) et Willie Anderson (1988, choix 10).<\/p>\n<p><strong>Les statistiques 2019-2020 d&rsquo;Anthony Edwards en NCAA avec Georgia :<\/strong> 19,1 points \u00e0 40% au tir dont 29% \u00e0 3 pts, 5,2 rebonds, 2,8 passes en 33 minutes de jeu (32 matchs).<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/nba-suivez-la-draft-2020-en-direct\/\" target=\"_blank\" rel=\"noopener noreferrer\">Suivez la suite de la Draft NBA 2020 en direct<\/a><\/strong><\/li>\n<\/ul>\n<p><em><strong>Mathieu Veillon<\/strong><\/em><br \/>\n<a href=\"https:\/\/twitter.com\/MathieuVeillon\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs. Dans un format visioconf\u00e9rence in\u00e9dit, la Draft 2020 a enfin livr\u00e9 son verdict et c&rsquo;est le jeune arri\u00e8re de 19 ans qui restera dans la post\u00e9rit\u00e9 comme le premier joueur de cette Draft.\u00a0<\/p>\n","protected":false},"author":21,"featured_media":88757,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[10533],"tags":[12557,12638,1992,179],"class_list":["post-88738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-draft-nba","tag-lamelo-ball","tag-minnesota-timberwolves","tag-nba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves<\/title>\n<meta name=\"description\" content=\"Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves\" \/>\n<meta property=\"og:description\" content=\"Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T01:13:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-19T01:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mathieu Veillon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/MathieuVeillon\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\"},\"author\":{\"name\":\"Mathieu Veillon\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806\"},\"headline\":\"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves\",\"datePublished\":\"2020-11-19T01:13:13+00:00\",\"dateModified\":\"2020-11-19T01:14:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg\",\"keywords\":[\"Draft NBA\",\"LaMelo Ball\",\"Minnesota Timberwolves\",\"NBA\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\",\"name\":\"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg\",\"datePublished\":\"2020-11-19T01:13:13+00:00\",\"dateModified\":\"2020-11-19T01:14:13+00:00\",\"description\":\"Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg\",\"width\":800,\"height\":445,\"caption\":\"Anthony Edwards (Photo Getty Images)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806\",\"name\":\"Mathieu Veillon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg\",\"caption\":\"Mathieu Veillon\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves","description":"Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/","og_locale":"fr_FR","og_type":"article","og_title":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves","og_description":"Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs.","og_url":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-11-19T01:13:13+00:00","article_modified_time":"2020-11-19T01:14:13+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg","type":"image\/jpeg"}],"author":"Mathieu Veillon","twitter_card":"summary_large_image","twitter_title":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves","twitter_creator":"@https:\/\/twitter.com\/MathieuVeillon","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/"},"author":{"name":"Mathieu Veillon","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806"},"headline":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves","datePublished":"2020-11-19T01:13:13+00:00","dateModified":"2020-11-19T01:14:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg","keywords":["Draft NBA","LaMelo Ball","Minnesota Timberwolves","NBA"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/","url":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/","name":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg","datePublished":"2020-11-19T01:13:13+00:00","dateModified":"2020-11-19T01:14:13+00:00","description":"Avec le premier choix de la Draft 2020, les Minnesota Timberwolves ont s\u00e9lectionn\u00e9 Anthony Edwards, des Georgia Bulldogs.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Anthony-Edwards-Draft-2020.jpg","width":800,"height":445,"caption":"Anthony Edwards (Photo Getty Images)"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/draft-nba-2020-anthony-edwards-selectionne-numero-1-par-les-wolves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Draft NBA 2020 : Anthony Edwards s\u00e9lectionn\u00e9 en n\u00b01 par les Wolves"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806","name":"Mathieu Veillon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","caption":"Mathieu Veillon"},"description":"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon"],"url":"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/88738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=88738"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/88738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/88757"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=88738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=88738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=88738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}