{"id":88977,"date":"2020-11-19T13:36:35","date_gmt":"2020-11-19T12:36:35","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=88977&#038;preview=true&#038;preview_id=88977"},"modified":"2020-11-19T15:46:05","modified_gmt":"2020-11-19T14:46:05","slug":"les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/","title":{"rendered":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/treizemondial.fr\/calendrier-et-resultats-super-league-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\">SUPER LEAGUE 2020<\/a> &#8211; Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Depuis 2014, les <a href=\"https:\/\/treizemondial.fr\/tag\/dragons-catalans\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Dragons Catalans<\/strong><\/a> n&rsquo;ont plus particip\u00e9 \u00e0 une demi-finale de <strong>Super League<\/strong>, et m\u00eame aux phases finales de la comp\u00e9tition. Toujours plac\u00e9s ou presque, il a toujours manqu\u00e9 quelque chose aux Dragons pour aller jouer le titre avec les meilleurs. En 2018, ils ont toutefois brillamment remport\u00e9 la <strong>Challenge Cup<\/strong> en \u00e9liminant St Helens en demi-finales, alors que les Anglais \u00e9taient largement favoris. Un peu comme cela sera le cas vendredi.<\/p>\n<p style=\"text-align: justify;\">De leur c\u00f4t\u00e9, les Saints sont les champions en titre de la Super League. S&rsquo;ils n&rsquo;ont termin\u00e9 qu&rsquo;\u00e0 la deuxi\u00e8me place de la phase r\u00e9guli\u00e8re, c&rsquo;est aussi parce que leur coach a souvent fait de larges revues d&rsquo;effectif pour pr\u00e9server des cadres au cours de cette saison aussi bizarre qu&rsquo;intense \u00e0 cause de la crise sanitaire. <strong>St Helens<\/strong> est l&rsquo;\u00e9quipe la plus impressionnante depuis la reprise en ao\u00fbt et avait d&rsquo;ailleurs douch\u00e9 les Dragons Catalans lors du premier match en ao\u00fbt, avec une large victoire (34-6). Mais pas de panique. En 2018, la donne \u00e9tait la m\u00eame ou presque avec une \u00e9quipe des Saints qui marchait sur tout le monde, avec sa superstar Ben Barba<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f409; Benjamin Jullien et Alrix Da Costa de retour pour la demi-finale &#x1f447;<a href=\"https:\/\/t.co\/USVxKgy69L\">https:\/\/t.co\/USVxKgy69L<\/a><\/p>\n<p>\u2014 Treize Mondial (@XIIIMondial) <a href=\"https:\/\/twitter.com\/XIIIMondial\/status\/1329034470117289984?ref_src=twsrc%5Etfw\">November 18, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Sam Tomkins &#8211; James Maloney, l&rsquo;heure des patrons<\/h2>\n<p style=\"text-align: justify;\">Les Dracs sont \u00e0 160 minutes de soulever leur deuxi\u00e8me troph\u00e9e dans les comp\u00e9titions anglaises. Le salut des Catalans passera par leurs deux stars, <strong>Sam Tomkins<\/strong> et <strong>James Maloney<\/strong>. Avec l&rsquo;absence pour suspension de Micky McIlorum, le r\u00f4le de <strong>James Maloney<\/strong> sera primordial, puisque le talonneur align\u00e9, Alrix Da Costa ou Benjamin Garcia, aura forc\u00e9ment moins d&rsquo;exp\u00e9rience que le Britannique. Le demi australien a \u00e9t\u00e9 parfait face aux perches lors du barrage mais a manqu\u00e9 un peu d&rsquo;impact dans le jeu de son \u00e9quipe. Ce dernier doit apporter encore plus via son exp\u00e9rience.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/treizemondial.fr\/sam-tomkins-au-presque-parfait\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sam Tomkins<\/strong> a lui \u00e9t\u00e9 exceptionnel<\/a> et pas que sur le match de barrages, mais bien sur toute cette deuxi\u00e8me partie de saison. L&rsquo;arri\u00e8re anglais est le d\u00e9tonateur de cette \u00e9quipe des <strong>Dragons Catalans<\/strong> et il faudra qu&rsquo;il soit \u00e0 son meilleur niveau pour battre St Helens. La saison a \u00e9t\u00e9 compliqu\u00e9e pour les joueurs catalans qui ont d\u00fb encha\u00eener les voyages en Angleterre, vivre des coupures de 15 jours \u00e0 cause de la Covid-19 et faire face \u00e0 une incertitude permanente de ce que sera fait le lendemain. Il faudra se servir de toutes ces \u00e9preuves pour afficher la m\u00eame agressivit\u00e9 que lors du match de barrages, et y ajouter encore plus de justesse technique pour ne faire aucun cadeau aux <strong>Saints<\/strong>.<\/p>\n<p style=\"text-align: justify;\">2020 est une ann\u00e9e que personne n&rsquo;oubliera \u00e0 cause de la pand\u00e9mie mondiale et qui a chang\u00e9 nos vies. Les amateurs de <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xiii\/\" target=\"_blank\" rel=\"noopener noreferrer\">rugby \u00e0 XIII<\/a> pourraient aussi s&rsquo;en souvenir gr\u00e2ce \u00e0 la premi\u00e8re victoire en <strong>Super League<\/strong> des <strong>Dragons Catalans<\/strong>. Deux matchs, 160 minutes, quelques centaines de plaquages et probablement plusieurs essais, voil\u00e0 ce qui les s\u00e9parent de pouvoir transformer ce r\u00eave en r\u00e9alit\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUPER LEAGUE &#8211; Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":88980,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9128],"tags":[5690,2049,5691,3795],"class_list":["post-88977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xiii","tag-dragons","tag-dragons-catalans","tag-st-helens","tag-super-league"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Dragons Catalans veulent refaire le coup de la Challenge Cup<\/title>\n<meta name=\"description\" content=\"SUPER LEAGUE - Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Dragons Catalans veulent refaire le coup de la Challenge Cup\" \/>\n<meta property=\"og:description\" content=\"SUPER LEAGUE - Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T12:36:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-19T14:46:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Dragons-Catalans-Casty-Langi-Folau.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les Dragons Catalans veulent refaire le coup de la Challenge Cup\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Les Dragons Catalans veulent refaire le coup de la Challenge Cup\",\"datePublished\":\"2020-11-19T12:36:35+00:00\",\"dateModified\":\"2020-11-19T14:46:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/\"},\"wordCount\":565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Dragons-Catalans-Casty-Langi-Folau.png\",\"keywords\":[\"Dragons\",\"Dragons Catalans\",\"St Helens\",\"Super League\"],\"articleSection\":[\"Rugby \u00e0 XIII\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/\",\"name\":\"Les Dragons Catalans veulent refaire le coup de la Challenge Cup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Dragons-Catalans-Casty-Langi-Folau.png\",\"datePublished\":\"2020-11-19T12:36:35+00:00\",\"dateModified\":\"2020-11-19T14:46:05+00:00\",\"description\":\"SUPER LEAGUE - Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Dragons-Catalans-Casty-Langi-Folau.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Dragons-Catalans-Casty-Langi-Folau.png\",\"width\":800,\"height\":445,\"caption\":\"Les Dragons Catalans veulent refaire le coup de la Challenge Cup\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Dragons Catalans veulent refaire le coup de la Challenge Cup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup","description":"SUPER LEAGUE - Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup","og_description":"SUPER LEAGUE - Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-11-19T12:36:35+00:00","article_modified_time":"2020-11-19T14:46:05+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Dragons-Catalans-Casty-Langi-Folau.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup","datePublished":"2020-11-19T12:36:35+00:00","dateModified":"2020-11-19T14:46:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/"},"wordCount":565,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Dragons-Catalans-Casty-Langi-Folau.png","keywords":["Dragons","Dragons Catalans","St Helens","Super League"],"articleSection":["Rugby \u00e0 XIII"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/","url":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/","name":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Dragons-Catalans-Casty-Langi-Folau.png","datePublished":"2020-11-19T12:36:35+00:00","dateModified":"2020-11-19T14:46:05+00:00","description":"SUPER LEAGUE - Les Dragons Catalans affrontent le tenant du titre, St Helens, pour une place en finale de la Super League 2020.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Dragons-Catalans-Casty-Langi-Folau.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Dragons-Catalans-Casty-Langi-Folau.png","width":800,"height":445,"caption":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-veulent-refaire-le-coup-de-la-challenge-cup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Dragons Catalans veulent refaire le coup de la Challenge Cup"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/88977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=88977"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/88977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/88980"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=88977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=88977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=88977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}