{"id":89293,"date":"2020-11-21T12:05:53","date_gmt":"2020-11-21T11:05:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=89293&#038;preview=true&#038;preview_id=89293"},"modified":"2020-11-22T08:20:13","modified_gmt":"2020-11-22T07:20:13","slug":"un-report-open-australie-2021-de-plus-en-plus-probable","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/","title":{"rendered":"Un report de l&rsquo;Open d&rsquo;Australie 2021 de plus en plus probable"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Selon nos confr\u00e8res du <a href=\"https:\/\/www.heraldsun.com.au\/subscribe\/news\/1\/?sourceCode=HSWEB_WRE170_a_TWT&amp;dest=https%3A%2F%2Fwww.heraldsun.com.au%2Fnews%2Faustralian-open-start-date-set-to-be-pushed-back%2Fnews-story%2Fc1ec1a1112fdc50589f05cc17d11a93d&amp;memtype=anonymous&amp;mode=premium&amp;nk=2be573aefd5b160282a14046799752db-1606029547\" target=\"_blank\" rel=\"noopener noreferrer\">Herald Sun<\/a>, l&rsquo;Open d&rsquo;Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">C&rsquo;\u00e9tait une rumeur il y a encore quelques jours, mais cela gagne en cr\u00e9dibilit\u00e9 ces derni\u00e8res heures. Il y a d\u00e9sormais tr\u00e8s peu de chances que l&rsquo;<a href=\"https:\/\/www.heraldsun.com.au\/subscribe\/news\/1\/?sourceCode=HSWEB_WRE170_a_TWT&amp;dest=https%3A%2F%2Fwww.heraldsun.com.au%2Fnews%2Faustralian-open-start-date-set-to-be-pushed-back%2Fnews-story%2Fc1ec1a1112fdc50589f05cc17d11a93d&amp;memtype=anonymous&amp;mode=premium&amp;nk=2be573aefd5b160282a14046799752db-1606029547\">Open d&rsquo;Australie<\/a> d\u00e9marre le 18 janvier 2021 comme cela \u00e9tait initialement pr\u00e9vu. Le Grand Chelem pourrait \u00eatre d\u00e9cal\u00e9 en f\u00e9vrier ou m\u00eame en mars afin de pr\u00e9parer au mieux l&rsquo;organisation du tournoi d&rsquo;un point de vue sanitaire.<\/p>\n<p style=\"text-align: justify;\">Daniel Andrews, premier ministre de l&rsquo;\u00e9tat de Victoria, a donn\u00e9 un peu plus de cr\u00e9dit \u00e0 la th\u00e8se du report :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Je suis tr\u00e8s confiant dans le fait que l&rsquo;Open d&rsquo;Australie aura lieu au d\u00e9but de l&rsquo;ann\u00e9e, a-t-il expliqu\u00e9. Je ne peux pas encore dire exactement quand ni dans quelles conditions, nous y travaillons. Et vous serez mis au courant d\u00e8s que nous aurons d\u00e9cid\u00e9.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">La saison 2021 de tennis risque de toute mani\u00e8re d&rsquo;\u00eatre chamboul\u00e9e par la crise sanitaire puisque tous les pays n&rsquo;en sont pas au m\u00eame stade dans la lutte contre le virus.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">LATEST: The Australian Open is almost certain not to begin on its scheduled 2021 start date of January 18, with the opening Grand Slam of the tennis calendar to be pushed back by months. <a href=\"https:\/\/t.co\/8Lj5nUplqJ\">https:\/\/t.co\/8Lj5nUplqJ<\/a><\/p>\n<p>\u2014 Herald Sun (@theheraldsun) <a href=\"https:\/\/twitter.com\/theheraldsun\/status\/1330065908870623233?ref_src=twsrc%5Etfw\">November 21, 2020<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon nos confr\u00e8res du Herald Sun, l&rsquo;Open d&rsquo;Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.<\/p>\n","protected":false},"author":1,"featured_media":89295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2302],"tags":[3226,136],"class_list":["post-89293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-open-daustralie","tag-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un report de l&#039;Open d&#039;Australie 2021 de plus en plus probable<\/title>\n<meta name=\"description\" content=\"Selon nos confr\u00e8res du Herald Sun, l&#039;Open d&#039;Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un report de l&#039;Open d&#039;Australie 2021 de plus en plus probable\" \/>\n<meta property=\"og:description\" content=\"Selon nos confr\u00e8res du Herald Sun, l&#039;Open d&#039;Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-21T11:05:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-22T07:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Open-dAustralie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Un report de l&#039;Open d&#039;Australie 2021 de plus en plus probable\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Un report de l&rsquo;Open d&rsquo;Australie 2021 de plus en plus probable\",\"datePublished\":\"2020-11-21T11:05:53+00:00\",\"dateModified\":\"2020-11-22T07:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Open-dAustralie.png\",\"keywords\":[\"Open d'Australie\",\"Tennis\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/\",\"name\":\"Un report de l'Open d'Australie 2021 de plus en plus probable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Open-dAustralie.png\",\"datePublished\":\"2020-11-21T11:05:53+00:00\",\"dateModified\":\"2020-11-22T07:20:13+00:00\",\"description\":\"Selon nos confr\u00e8res du Herald Sun, l'Open d'Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Open-dAustralie.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Open-dAustralie.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/un-report-open-australie-2021-de-plus-en-plus-probable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un report de l&rsquo;Open d&rsquo;Australie 2021 de plus en plus probable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un report de l'Open d'Australie 2021 de plus en plus probable","description":"Selon nos confr\u00e8res du Herald Sun, l'Open d'Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/","og_locale":"fr_FR","og_type":"article","og_title":"Un report de l'Open d'Australie 2021 de plus en plus probable","og_description":"Selon nos confr\u00e8res du Herald Sun, l'Open d'Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.","og_url":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-11-21T11:05:53+00:00","article_modified_time":"2020-11-22T07:20:13+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Open-dAustralie.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Un report de l'Open d'Australie 2021 de plus en plus probable","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Un report de l&rsquo;Open d&rsquo;Australie 2021 de plus en plus probable","datePublished":"2020-11-21T11:05:53+00:00","dateModified":"2020-11-22T07:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Open-dAustralie.png","keywords":["Open d'Australie","Tennis"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/","url":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/","name":"Un report de l'Open d'Australie 2021 de plus en plus probable","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Open-dAustralie.png","datePublished":"2020-11-21T11:05:53+00:00","dateModified":"2020-11-22T07:20:13+00:00","description":"Selon nos confr\u00e8res du Herald Sun, l'Open d'Australie 2021 pourrait \u00eatre report\u00e9 de quelques semaines.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Open-dAustralie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/Open-dAustralie.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/un-report-open-australie-2021-de-plus-en-plus-probable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Un report de l&rsquo;Open d&rsquo;Australie 2021 de plus en plus probable"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/89293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=89293"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/89293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/89295"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=89293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=89293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=89293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}