{"id":90618,"date":"2020-11-29T16:05:15","date_gmt":"2020-11-29T15:05:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=90618&#038;preview=true&#038;preview_id=90618"},"modified":"2021-10-18T16:40:06","modified_gmt":"2021-10-18T14:40:06","slug":"xv-de-france-les-31-bleus-pour-la-finale-face-angleterre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/","title":{"rendered":"XV de France : Les 31 Bleus pour la finale face \u00e0 l&rsquo;Angleterre"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>AUTUMN NATIONS CUP &#8211; Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l&rsquo;Angleterre (dimanche 6\/12 \u00e0 15h).<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Au total, six changements dans le groupe du <a href=\"https:\/\/dicodusport.fr\/blog\/tag\/xv-de-france\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>XV de France<\/strong><\/a>, dont deux forc\u00e9s par la r\u00e8gle des trois feuilles de match (Serin et Thomas). <strong>S\u00e9bastien B\u00e9zy (Clermont)<\/strong> et <strong>Donovan Taofifenua (Racing 92)<\/strong> arrivent ainsi \u00e0 Marcoussis. Quatre autres joueurs int\u00e8grent ce groupe pour cette derni\u00e8re rencontre de l&rsquo;automne 2020 : <strong>Anthony \u00c9trillard<\/strong>, <strong>Selevasio Tolofua<\/strong>, <strong>Pierre-Louis Barassi<\/strong> et <strong>Guillaume Ducat<\/strong>. Fabien Galthi\u00e9 a expliqu\u00e9 apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/le-xv-de-france-domine-litalie-en-deux-temps\/\" target=\"_blank\" rel=\"noopener noreferrer\">la victoire face \u00e0 l&rsquo;Italie (36-5)<\/a> qu&rsquo;il devrait r\u00e9utiliser la m\u00eame ossature face \u00e0 l&rsquo;Angleterre.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3f4;&#xe0067;&#xe0062;&#xe0065;&#xe006e;&#xe0067;&#xe007f;&#x1f1eb;&#x1f1f7; <a href=\"https:\/\/twitter.com\/FGalthie?ref_src=twsrc%5Etfw\">@FGalthie<\/a> et <a href=\"https:\/\/twitter.com\/ibanez_raphael?ref_src=twsrc%5Etfw\">@ibanez_raphael<\/a> ont annonc\u00e9 les 31 joueurs qui pr\u00e9pareront la finale de l&rsquo;<a href=\"https:\/\/twitter.com\/autumnnations?ref_src=twsrc%5Etfw\">@autumnnations<\/a> dimanche prochain contre l&rsquo;Angleterre !<a href=\"https:\/\/twitter.com\/hashtag\/NeFaisonsXV?src=hash&amp;ref_src=twsrc%5Etfw\">#NeFaisonsXV<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/XVdeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#XVdeFrance<\/a> <a href=\"https:\/\/t.co\/VRtHG8j0IC\">pic.twitter.com\/VRtHG8j0IC<\/a><\/p>\n<p>\u2014 France Rugby (@FranceRugby) <a href=\"https:\/\/twitter.com\/FranceRugby\/status\/1333046197133713412?ref_src=twsrc%5Etfw\">November 29, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AUTUMN NATIONS CUP &#8211; Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l&rsquo;Angleterre (dimanche 6\/12 \u00e0 15h).<\/p>\n","protected":false},"author":1,"featured_media":90628,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,19951],"tags":[51,11639,1638],"class_list":["post-90618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-angleterre","tag-autumn-nations-cup","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XV de France : Les 31 Bleus pour la finale face \u00e0 l&#039;Angleterre<\/title>\n<meta name=\"description\" content=\"AUTUMN NATIONS CUP - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l&#039;Angleterre (dimanche 6\/12 \u00e0 15h).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : Les 31 Bleus pour la finale face \u00e0 l&#039;Angleterre\" \/>\n<meta property=\"og:description\" content=\"AUTUMN NATIONS CUP - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l&#039;Angleterre (dimanche 6\/12 \u00e0 15h).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-29T15:05:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T14:40:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : Les 31 Bleus pour la finale face \u00e0 l&#039;Angleterre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"XV de France : Les 31 Bleus pour la finale face \u00e0 l&rsquo;Angleterre\",\"datePublished\":\"2020-11-29T15:05:15+00:00\",\"dateModified\":\"2021-10-18T14:40:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/\"},\"wordCount\":170,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png\",\"keywords\":[\"Angleterre\",\"Autumn Nations Cup\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/\",\"name\":\"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png\",\"datePublished\":\"2020-11-29T15:05:15+00:00\",\"dateModified\":\"2021-10-18T14:40:06+00:00\",\"description\":\"AUTUMN NATIONS CUP - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l'Angleterre (dimanche 6\\\/12 \u00e0 15h).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png\",\"width\":800,\"height\":445,\"caption\":\"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : Les 31 Bleus pour la finale face \u00e0 l&rsquo;Angleterre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre","description":"AUTUMN NATIONS CUP - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l'Angleterre (dimanche 6\/12 \u00e0 15h).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre","og_description":"AUTUMN NATIONS CUP - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l'Angleterre (dimanche 6\/12 \u00e0 15h).","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-11-29T15:05:15+00:00","article_modified_time":"2021-10-18T14:40:06+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"XV de France : Les 31 Bleus pour la finale face \u00e0 l&rsquo;Angleterre","datePublished":"2020-11-29T15:05:15+00:00","dateModified":"2021-10-18T14:40:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/"},"wordCount":170,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png","keywords":["Angleterre","Autumn Nations Cup","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/","name":"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png","datePublished":"2020-11-29T15:05:15+00:00","dateModified":"2021-10-18T14:40:06+00:00","description":"AUTUMN NATIONS CUP - Fabien Galthi\u00e9 a d\u00e9voil\u00e9 un groupe de 31 joueurs pour la finale face \u00e0 l'Angleterre (dimanche 6\/12 \u00e0 15h).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/11\/XV-de-France-Les-31-Bleus-pour-la-finale-face-\u00e0-lAngleterre.png","width":800,"height":445,"caption":"XV de France : Les 31 Bleus pour la finale face \u00e0 l'Angleterre"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-les-31-bleus-pour-la-finale-face-angleterre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : Les 31 Bleus pour la finale face \u00e0 l&rsquo;Angleterre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/90618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=90618"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/90618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/90628"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=90618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=90618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=90618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}