{"id":92323,"date":"2020-12-09T14:40:21","date_gmt":"2020-12-09T13:40:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=92323&#038;preview=true&#038;preview_id=92323"},"modified":"2021-05-11T17:00:28","modified_gmt":"2021-05-11T15:00:28","slug":"football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/","title":{"rendered":"Football &#8211; Ligue Europa : notre pronostic pour Hapoel Beer-Sheva &#8211; Nice"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE EUROPA &#8211; L&rsquo;Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Hapoel Beer-Sheva &#8211; Nice : Jeudi 10 d\u00e9cembre, 18h55<\/h2>\n<p style=\"text-align: justify;\">Le club isra\u00e9lien n&rsquo;a pas d\u00e9m\u00e9rit\u00e9 dans ses matchs \u00e0 la maison en Coupe d&rsquo;Europe avec une victoire contre le Sparta Prague et un bon match face \u00e0 Leverkusen m\u00eame s&rsquo;il y a eu la d\u00e9faite au bout. Nice est en plein cauchemar et ne parvient pas \u00e0 sortir la t\u00eate de l&rsquo;eau. Patrick Vieira a perdu son poste d&rsquo;entra\u00eeneur mais pas s\u00fbr que cela soit suffisant pour redresser la barre. \u00c0 l&rsquo;aller, les Ni\u00e7ois avaient eu toutes les peines du monde \u00e0 battre Beer-Sheva et ils ne jouent plus rien sur ce match retour ce qui devrait entra\u00eener une rotation de l&rsquo;effectif. On part sur <strong>une victoire de l&rsquo;Hapoel Beer-Sheva ou un nul avec plus d&rsquo;1,5 buts dans le match<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; height: 23px; vertical-align: middle; width: 600px;\"><span style=\"font-size: 12px; color: #ffffff;\">Jeudi 10 d\u00e9cembre, 18h55<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; text-align: center; vertical-align: middle; width: 200px;\"><span style=\"font-size: 12px; color: #ffffff;\">1N &amp; +1,5 buts<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; height: 47px; width: 600px;\"><strong>Hapoel Beer-Sheva &#8211; Nice<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; height: 47px; text-align: center; vertical-align: middle; width: 200px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/23831941?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> 1.76<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE EUROPA &#8211; L&rsquo;Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.<\/p>\n","protected":false},"author":1,"featured_media":92336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[75,4437,460,4949],"class_list":["post-92323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-ligue-europa","tag-nice","tag-pronostics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Football - Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice - Dicodusport<\/title>\n<meta name=\"description\" content=\"LIGUE EUROPA - L&#039;Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice\" \/>\n<meta property=\"og:description\" content=\"LIGUE EUROPA - L&#039;Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-09T13:40:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T15:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Football &#8211; Ligue Europa : notre pronostic pour Hapoel Beer-Sheva &#8211; Nice\",\"datePublished\":\"2020-12-09T13:40:21+00:00\",\"dateModified\":\"2021-05-11T15:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/\"},\"wordCount\":222,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png\",\"keywords\":[\"Football\",\"Ligue Europa\",\"Nice\",\"Pronostics\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/\",\"name\":\"Football - Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png\",\"datePublished\":\"2020-12-09T13:40:21+00:00\",\"dateModified\":\"2021-05-11T15:00:28+00:00\",\"description\":\"LIGUE EUROPA - L'Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png\",\"width\":1200,\"height\":670,\"caption\":\"Football - Ligue Europa notre pronostic pour Hapoel Beer-Sheva - Nice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Football &#8211; Ligue Europa : notre pronostic pour Hapoel Beer-Sheva &#8211; Nice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Football - Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice - Dicodusport","description":"LIGUE EUROPA - L'Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice","og_description":"LIGUE EUROPA - L'Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-12-09T13:40:21+00:00","article_modified_time":"2021-05-11T15:00:28+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Football &#8211; Ligue Europa : notre pronostic pour Hapoel Beer-Sheva &#8211; Nice","datePublished":"2020-12-09T13:40:21+00:00","dateModified":"2021-05-11T15:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/"},"wordCount":222,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png","keywords":["Football","Ligue Europa","Nice","Pronostics"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/","url":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/","name":"Football - Ligue Europa : notre pronostic pour Hapoel Beer-Sheva - Nice - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png","datePublished":"2020-12-09T13:40:21+00:00","dateModified":"2021-05-11T15:00:28+00:00","description":"LIGUE EUROPA - L'Hapoel Beer-Sheva re\u00e7oit Nice pour la 6\u00e8me journ\u00e9e de la Ligue Europa 2020-2021. Notre pronostic pour la rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-Europa-notre-pronostic-pour-Hapoel-Beer-Sheva-Nice.png","width":1200,"height":670,"caption":"Football - Ligue Europa notre pronostic pour Hapoel Beer-Sheva - Nice"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-europa-notre-pronostic-pour-hapoel-beer-sheva-nice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Football &#8211; Ligue Europa : notre pronostic pour Hapoel Beer-Sheva &#8211; Nice"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/92323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=92323"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/92323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/92336"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=92323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=92323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=92323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}