{"id":93862,"date":"2020-12-18T15:43:20","date_gmt":"2020-12-18T14:43:20","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=93862&#038;preview=true&#038;preview_id=93862"},"modified":"2021-05-11T16:59:35","modified_gmt":"2021-05-11T14:59:35","slug":"football-ligue-1-notre-pronostic-pour-nice-lyon","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/","title":{"rendered":"Football &#8211; Ligue 1 : notre pronostic pour Nice &#8211; Lyon"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-ligue-1-2020-2021-16eme-journee-programme-et-resultats\/\" target=\"_blank\" rel=\"noopener noreferrer\">LIGUE 1 &#8211; 16\u00c8ME JOURN\u00c9E<\/a> &#8211; Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Nice &#8211; Lyon : Samedi 19 d\u00e9cembre, 21h00<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s une s\u00e9rie de 7 d\u00e9faites en 8 matchs, Nice s&rsquo;est enfin relanc\u00e9 en dominant N\u00eemes en milieu de semaine, une victoire qui permet aux Aiglons de recoller au bon groupe au classement. L&rsquo;Olympique Lyonnais peut avoir des regrets sur son match de la semaine, un nul conc\u00e9d\u00e9 alors que Brest \u00e9tait \u00e0 10. Lyon sera favori de ce duel mais Nice peut surfer sur sa bonne lanc\u00e9e pour les accrocher donc on ne pr\u00e9f\u00e8re pas partir sur l&rsquo;issue et on donne <strong>les deux \u00e9quipes qui marquent<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; border-color: #ededed; height: 23px; width: 580px; vertical-align: middle;\"><span style=\"font-size: 12px; color: #ffffff;\">Mercredi 16 d\u00e9cembre, 21h00<\/span><\/td>\n<td style=\"background-color: #525252; width: 300px; border-color: #ededed; text-align: center; vertical-align: middle;\" colspan=\"2\"><span style=\"font-size: 12px; color: #ffffff;\">Les deux \u00e9quipes vont-elles marquer ?\u00a0<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; height: 47px; width: 580px;\"><strong>Nice &#8211; Lyon<br \/>\n<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; width: 150px; height: 47px; text-align: center; vertical-align: middle;\"><span style=\"font-size: 14px;\">Oui<\/span><br \/>\n<span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22650641?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d8ac7;border-radius:5px;text-shadow:none\"> 1.66<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; width: 150px; height: 47px; text-align: center; vertical-align: middle;\"><span style=\"font-size: 14px;\">Non<\/span><br \/>\n<span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/22650641?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b10e12;border-color:#8e0c0f;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#c9575a;border-radius:5px;text-shadow:none\"> 1.90<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 &#8211; 16\u00c8ME JOURN\u00c9E &#8211; Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.<\/p>\n","protected":false},"author":1,"featured_media":93903,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[75,1554,449,460,4949],"class_list":["post-93862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-ligue-1","tag-lyon","tag-nice","tag-pronostics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Football - Ligue 1 : notre pronostic pour Nice - Lyon - Dicodusport<\/title>\n<meta name=\"description\" content=\"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 : notre pronostic pour Nice - Lyon\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-18T14:43:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T14:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue 1 : notre pronostic pour Nice - Lyon\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Football &#8211; Ligue 1 : notre pronostic pour Nice &#8211; Lyon\",\"datePublished\":\"2020-12-18T14:43:20+00:00\",\"dateModified\":\"2021-05-11T14:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png\",\"keywords\":[\"Football\",\"Ligue 1\",\"Lyon\",\"Nice\",\"Pronostics\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/\",\"name\":\"Football - Ligue 1 : notre pronostic pour Nice - Lyon - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png\",\"datePublished\":\"2020-12-18T14:43:20+00:00\",\"dateModified\":\"2021-05-11T14:59:35+00:00\",\"description\":\"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png\",\"width\":1200,\"height\":670,\"caption\":\"Football - Ligue 1 notre pronostic pour Nice - Lyon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/football-ligue-1-notre-pronostic-pour-nice-lyon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Football &#8211; Ligue 1 : notre pronostic pour Nice &#8211; Lyon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Football - Ligue 1 : notre pronostic pour Nice - Lyon - Dicodusport","description":"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 : notre pronostic pour Nice - Lyon","og_description":"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2020-12-18T14:43:20+00:00","article_modified_time":"2021-05-11T14:59:35+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Ligue 1 : notre pronostic pour Nice - Lyon","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Football &#8211; Ligue 1 : notre pronostic pour Nice &#8211; Lyon","datePublished":"2020-12-18T14:43:20+00:00","dateModified":"2021-05-11T14:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png","keywords":["Football","Ligue 1","Lyon","Nice","Pronostics"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/","url":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/","name":"Football - Ligue 1 : notre pronostic pour Nice - Lyon - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png","datePublished":"2020-12-18T14:43:20+00:00","dateModified":"2021-05-11T14:59:35+00:00","description":"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Nice re\u00e7oit Lyon dans le cadre de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/12\/Football-Ligue-1-notre-pronostic-pour-Nice-Lyon.png","width":1200,"height":670,"caption":"Football - Ligue 1 notre pronostic pour Nice - Lyon"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/football-ligue-1-notre-pronostic-pour-nice-lyon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Football &#8211; Ligue 1 : notre pronostic pour Nice &#8211; Lyon"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/93862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=93862"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/93862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/93903"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=93862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=93862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=93862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}