{"id":99310,"date":"2021-01-15T15:31:01","date_gmt":"2021-01-15T14:31:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=99310"},"modified":"2021-01-15T16:34:42","modified_gmt":"2021-01-15T15:34:42","slug":"qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/","title":{"rendered":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>BASKET &#8211; Alors qu&rsquo;il reste 2 matchs \u00e0 disputer, Vincent Collet a d\u00e9voil\u00e9 ce jour les joueurs retenus en vue des qualifications pour l&rsquo;Euro 2022.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Ils y sont presque mais le travail reste \u00e0 finir. Leaders de leur poule les <em>Bleus<\/em> auront besoin d&rsquo;une victoire pour lors deux derni\u00e8res rencontres pour valider leur billet pour <strong>l&rsquo;Euro 2022<\/strong>. Pour ce faire, l&rsquo;entra\u00eeneur <strong>Vincent Collet<\/strong> et le manager g\u00e9n\u00e9ral <strong>Patrick<\/strong> <strong>Beesley<\/strong> ont retenu 12 joueurs. Pour le premier de ces deux matchs les tricolores affronteront le <strong>Montenegro Sportski au Centar Moraca de Podgorica<\/strong> . Ensuite deux jours plus tard, ils recevront la <strong>Grande-Bretagne<\/strong>. Leader de la poule les <em>Bleus<\/em> doivent terminer \u00e0 l&rsquo;une des deux premi\u00e8res places. Lanterne rouge mais pays h\u00f4te de cet <strong>Euro, les Allemands<\/strong> sont quant \u00e0 eux d&rsquo;ores et d\u00e9j\u00e0 qualifi\u00e9s. Il en est de m\u00eame pour les 3 autres pays h\u00f4tes :<strong> l&rsquo;Italie, la G\u00e9orgie et la R\u00e9publique Tch\u00e8que<\/strong>. Le tournoi s<span class=\"ILfuVd\"><span class=\"hgKElc\">e tiendra du 1<sup>er<\/sup> septembre au 18 septembre 2022.<\/span><\/span><\/p>\n<h2 style=\"text-align: justify;\">Voici la liste des 12 joueurs retenus qui se r\u00e9uniront au pr\u00e9alable du 17 au 19 f\u00e9vrier prochain \u00e0 Nanterre<\/h2>\n<p style=\"text-align: justify;\"><strong>Andrew Albicy (CB Gran Canaria), Axel Julien (JDA Dijon), Thomas Heurtel (FC Barcelone), Isa\u00efa Cordinier (Nanterre 92), Axel Bouteille (Bilbao Basket), Lahaou Konate (Metropolitans 92), Yakuba Ouattara (Coosur Real Betis), Maxime Roos (Metropolitans 92), Amath M&rsquo;Baye (Pinar Karsiyaka) SK Alexandre Chassang (JDA Dijon), Mathias Lessort (AS Monaco) et Jerry Boutsiel (Limoges CSP).<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/eurobasket-masculin-2022-programme-des-qualifications\/\" target=\"_blank\" rel=\"noopener noreferrer\">EuroBasket 2022 masculin : programme des qualifications<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><em>Julien Correia<br \/>\n<a href=\"https:\/\/www.facebook.com\/julien.correia.52\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/julienco_psg70\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BASKET &#8211; Alors qu&rsquo;il reste 2 matchs \u00e0 disputer, Vincent Collet a d\u00e9voil\u00e9 ce jour les joueurs retenus en vue des qualifications pour l&rsquo;Euro 2022.<\/p>\n","protected":false},"author":37,"featured_media":99334,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305],"tags":[295,199,8441],"class_list":["post-99310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basket-ball","tag-equipe-de-france","tag-vincent-collet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus<\/title>\n<meta name=\"description\" content=\"Vincent Collet a d\u00e9voil\u00e9 ce jour les 12 joueurs retenus en vue des qualifications pour l&#039;Euro 2022 de basket-ball\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus\" \/>\n<meta property=\"og:description\" content=\"Vincent Collet a d\u00e9voil\u00e9 ce jour les 12 joueurs retenus en vue des qualifications pour l&#039;Euro 2022 de basket-ball\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/julien.correia.52\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T14:31:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-15T15:34:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julien Correia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/julienco_psg70\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\"},\"author\":{\"name\":\"Julien Correia\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239\"},\"headline\":\"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus\",\"datePublished\":\"2021-01-15T14:31:01+00:00\",\"dateModified\":\"2021-01-15T15:34:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png\",\"keywords\":[\"Basket-ball\",\"\u00c9quipe de France\",\"Vincent Collet\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\",\"name\":\"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png\",\"datePublished\":\"2021-01-15T14:31:01+00:00\",\"dateModified\":\"2021-01-15T15:34:42+00:00\",\"description\":\"Vincent Collet a d\u00e9voil\u00e9 ce jour les 12 joueurs retenus en vue des qualifications pour l'Euro 2022 de basket-ball\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png\",\"width\":800,\"height\":445,\"caption\":\"Qualifications EuroBasket 2022 - Vincent Collet d\u00e9voile les 12 joueurs retenus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239\",\"name\":\"Julien Correia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg\",\"caption\":\"Julien Correia\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis janvier 2019 - Tomb\u00e9 dans le monde du ballon rond \u00e9tant petit, j\u2019aurais pu devenir pro sans ces foutus ligaments crois\u00e9s. D\u00e9filant sur les champs (mais pas Elys\u00e9es) en 98, j\u2019ai \u00e9t\u00e9 berc\u00e9 par les exploits de Mister George, piqu\u00e9 par la technique du Snake, grandi avec Captain Rai et Ronnie, m\u00fbri avec Pauleta et Edi. Mais Ibracadabra, je suis d\u00e9sormais reconverti en runner\/traileur. Moins rapide que Bolt et moins endurant que Jornet, c\u2019est donc plume \u00e0 la main que je partage les exploits de ces athl\u00e8tes !\",\"sameAs\":[\"https:\/\/www.facebook.com\/julien.correia.52\",\"https:\/\/x.com\/https:\/\/twitter.com\/julienco_psg70\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/julien-c\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus","description":"Vincent Collet a d\u00e9voil\u00e9 ce jour les 12 joueurs retenus en vue des qualifications pour l'Euro 2022 de basket-ball","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/","og_locale":"fr_FR","og_type":"article","og_title":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus","og_description":"Vincent Collet a d\u00e9voil\u00e9 ce jour les 12 joueurs retenus en vue des qualifications pour l'Euro 2022 de basket-ball","og_url":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/julien.correia.52","article_published_time":"2021-01-15T14:31:01+00:00","article_modified_time":"2021-01-15T15:34:42+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png","type":"image\/png"}],"author":"Julien Correia","twitter_card":"summary_large_image","twitter_title":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus","twitter_creator":"@https:\/\/twitter.com\/julienco_psg70","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/"},"author":{"name":"Julien Correia","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239"},"headline":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus","datePublished":"2021-01-15T14:31:01+00:00","dateModified":"2021-01-15T15:34:42+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png","keywords":["Basket-ball","\u00c9quipe de France","Vincent Collet"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/","url":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/","name":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png","datePublished":"2021-01-15T14:31:01+00:00","dateModified":"2021-01-15T15:34:42+00:00","description":"Vincent Collet a d\u00e9voil\u00e9 ce jour les 12 joueurs retenus en vue des qualifications pour l'Euro 2022 de basket-ball","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/01\/Qualifications-EuroBasket-2022-Vincent-Collet-d\u00e9voile-les-12-joueurs-retenus.png","width":800,"height":445,"caption":"Qualifications EuroBasket 2022 - Vincent Collet d\u00e9voile les 12 joueurs retenus"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/qualifications-eurobasket-2022-vincent-collet-devoile-les-12-joueurs-retenus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Qualifications EuroBasket 2022 : Vincent Collet d\u00e9voile les 12 joueurs retenus"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239","name":"Julien Correia","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg","caption":"Julien Correia"},"description":"Journaliste\/r\u00e9dacteur depuis janvier 2019 - Tomb\u00e9 dans le monde du ballon rond \u00e9tant petit, j\u2019aurais pu devenir pro sans ces foutus ligaments crois\u00e9s. D\u00e9filant sur les champs (mais pas Elys\u00e9es) en 98, j\u2019ai \u00e9t\u00e9 berc\u00e9 par les exploits de Mister George, piqu\u00e9 par la technique du Snake, grandi avec Captain Rai et Ronnie, m\u00fbri avec Pauleta et Edi. Mais Ibracadabra, je suis d\u00e9sormais reconverti en runner\/traileur. Moins rapide que Bolt et moins endurant que Jornet, c\u2019est donc plume \u00e0 la main que je partage les exploits de ces athl\u00e8tes !","sameAs":["https:\/\/www.facebook.com\/julien.correia.52","https:\/\/x.com\/https:\/\/twitter.com\/julienco_psg70"],"url":"https:\/\/dicodusport.fr\/blog\/author\/julien-c\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/99310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=99310"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/99310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/99334"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=99310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=99310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=99310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}